{"id":40947,"date":"2022-03-21T14:21:52","date_gmt":"2022-03-21T13:21:52","guid":{"rendered":"https:\/\/www.vebs.de\/les-ecoles-confessionnelles-libres-un-droit-fondamental-si-les-conditions-sont-remplies-et-le-restent\/"},"modified":"2025-06-26T08:42:02","modified_gmt":"2025-06-26T06:42:02","slug":"les-ecoles-confessionnelles-libres-un-droit-fondamental-si-les-conditions-sont-remplies-et-le-restent","status":"publish","type":"post","link":"https:\/\/www.vebs.de\/fr\/les-ecoles-confessionnelles-libres-un-droit-fondamental-si-les-conditions-sont-remplies-et-le-restent\/","title":{"rendered":"Les \u00e9coles confessionnelles libres - un droit fondamental, si les conditions sont remplies et le restent !"},"content":{"rendered":"\n<p>Pendant cinq ans, le gouvernement du Land de Hambourg avait alors tent\u00e9 d&#8217;emp\u00eacher l&rsquo;\u00e9cole primaire de l&rsquo;initiative parentale. La raison en \u00e9tait la suivante : Les \u00e9coles confessionnelles ne pouvaient \u00eatre fond\u00e9es que par les grandes \u00e9glises. Depuis le 19 f\u00e9vrier 1992, il est clair que cette opinion des autorit\u00e9s \u00e9tait erron\u00e9e. \"N&rsquo;importe quelle confession de foi\", par exemple la \"base commune de la foi de l&rsquo;Alliance \u00e9vang\u00e9lique\", est suffisante comme base de confession de foi pour une \u00e9cole primaire libre en tant qu&rsquo;\u00e9cole confessionnelle.   <\/p>\n\n<p>Cette clarification de la disposition constitutionnelle de l&rsquo;article 6 de notre loi fondamentale a conduit \u00e0 la cr\u00e9ation de nombreuses autres \u00e9coles par des parents protestants : 30 ans plus tard, on compte \u00e0 elles seules plus de 150 \u00e9coles confessionnelles qui ont pour base confessionnelle la Bible, le Credo apostolique et la base de foi de l&rsquo;Alliance \u00e9vang\u00e9lique.<\/p>\n\n<p>Aussi important qu&rsquo;ait \u00e9t\u00e9 le jugement pour la fondation des nombreuses \u00e9coles confessionnelles chr\u00e9tiennes, il est vite tomb\u00e9 dans l&rsquo;oubli pour beaucoup des fondateurs d&rsquo;\u00e9coles de l&rsquo;\u00e9poque et encore plus pour leurs successeurs. Les \u00e9coles semblaient ne pas pouvoir croire qu&rsquo;un jugement de la plus haute juridiction allemande en mati\u00e8re administrative avait donn\u00e9 raison \u00e0 100 % \u00e0 leur demande ! <\/p>\n\n<p>En fait, le tribunal administratif f\u00e9d\u00e9ral avait compl\u00e8tement rejet\u00e9 la conception administrative de l&rsquo;article 7, paragraphe 5, de la Loi fondamentale qui pr\u00e9valait depuis des d\u00e9cennies. D\u00e9sormais, il ne sera plus question de savoir si une \u00e9cole accepte la confession d&rsquo;une \u00e9glise protestante r\u00e9gionale - les \u00e9coles protestantes \"libres\" sont autoris\u00e9es. Une \"confession quelconque\", \u00e0 laquelle s&rsquo;applique la libert\u00e9 de confession et de foi de l&rsquo;article 4, paragraphe 1, de la Loi fondamentale, peut depuis 1992 servir de base \u00e0 une \u00e9cole confessionnelle.  <\/p>\n\n<p>Ce qui constitue une confession et comment elle est d\u00e9finie a \u00e9t\u00e9 ciment\u00e9 par le tribunal administratif f\u00e9d\u00e9ral le 19 f\u00e9vrier 1992 pour les \u00e9coles primaires dans deux jugements : Un jugement concernant les \u00e9coles de conviction (la demande d&rsquo;autorisation d&rsquo;une \u00e9cole de scientologie a \u00e9t\u00e9 rejet\u00e9e parce que la scientologie n&rsquo;\u00e9tait pas une \"conviction\") portant le num\u00e9ro de dossier 6 C 5.91 et un jugement concernant \"notre\" \u00e9cole de conviction de Hambourg (le souhait des fondateurs de l&rsquo;\u00e9cole a \u00e9t\u00e9 approuv\u00e9) portant le num\u00e9ro de dossier 6 C 3.91. La d\u00e9cision de la Cour supr\u00eame de l&rsquo;Allemagne a \u00e9t\u00e9 rendue le 18 novembre 1991.<\/p>\n\n<p>Dans \"notre\" jugement, le tribunal a fait des r\u00e9f\u00e9rences \u00e0 son jugement sur les \u00e9coles de conviction, c&rsquo;est pourquoi nous ins\u00e9rons aux endroits concern\u00e9s les phrases cl\u00e9s du jugement sur les \u00e9coles de conviction - mais pour \u00eatre pr\u00e9cis, nous parlons toujours des deux jugements de ce jour.<\/p>\n\n<p>Mais : les droits s&rsquo;accompagnent aussi d&rsquo;obligations, c&rsquo;est-\u00e0-dire de conditions qui doivent \u00eatre remplies ! Le tribunal administratif f\u00e9d\u00e9ral dit tr\u00e8s clairement une chose : une \u00e9cole confessionnelle doit obligatoirement avoir une communaut\u00e9 confessionnelle largement homog\u00e8ne. Cela signifie que les parents non croyants et leurs enfants sont autoris\u00e9s en tant que minorit\u00e9 \"silencieuse\" si  <\/p>\n\n<ul class=\"wp-block-list\"><li>veulent au moins conna\u00eetre notre confession de foi (\"accepter\" ne suffit pas)<\/li><li>et qu&rsquo;ils ne perturbent pas, par leur diff\u00e9rence, l&rsquo;aspect confessionnel de la vie scolaire.<\/li><\/ul>\n\n<p>En d&rsquo;autres termes, le quotidien scolaire et l&rsquo;enseignement d&rsquo;une \u00e9cole confessionnelle doivent \u00eatre marqu\u00e9s par sa confession (premier principe de l&rsquo;arr\u00eat) - sans contradiction de la part de ceux qui ne partagent pas (encore) notre confession. Si cette empreinte confessionnelle fait d\u00e9faut ou dispara\u00eet, une telle \u00e9cole primaire devrait \u00eatre ferm\u00e9e par les autorit\u00e9s ! <\/p>\n\n<p>Apr\u00e8s le jugement de 1992, ces conditions obligatoires pour les \u00e9coles confessionnelles libres n&rsquo;ont plus \u00e9t\u00e9 respect\u00e9es avec autant d&rsquo;attention, ni par les fondateurs d&rsquo;\u00e9coles, ni par les autorit\u00e9s<strong>. <\/strong>Les L\u00e4nder, \u00e0 l&rsquo;exception de la Bavi\u00e8re, ont certes appliqu\u00e9 le jugement en ce qui concerne la confession possible, mais pour le reste, ils en sont rest\u00e9s plus ou moins aux conditions d\u00e9j\u00e0 exig\u00e9es auparavant, selon lesquelles les \u00e9coles confessionnelles (anciennement religieuses) devaient, en tant qu&rsquo;\u00e9coles de substitution, correspondre dans une large mesure aux \u00e9coles publiques.<\/p>\n\n<p>Coup de th\u00e9\u00e2tre du tribunal administratif de Stuttgart en 2003 : la fondation d&rsquo;une \u00e9cole islamique ne peut pas \u00eatre autoris\u00e9e !<\/p>\n\n<p>Les choses ont chang\u00e9 en 2003, lorsque le minist\u00e8re de l&rsquo;\u00e9ducation du Bade-Wurtemberg a rejet\u00e9 la demande d&rsquo;autorisation pour une \u00e9cole confessionnelle islamique pr\u00e9vue \u00e0 Stuttgart et que les plaignants ont \u00e9chou\u00e9 en premi\u00e8re instance avec leur plainte contre cette \u00e9cole, malgr\u00e9 la pr\u00e9sence de bons avocats, parce qu&rsquo;ils n&rsquo;avaient pas tenu compte des jugements de 1992. Contrairement aux courageux parents hambourgeois, ils n&rsquo;ont pas fait appel, mais ont capitul\u00e9. <\/p>\n\n<p>En effet, le jugement \u00e9tait \"\u00e9tanche\" : la Cour avait motiv\u00e9 sa d\u00e9cision sur la base des arr\u00eats de 1992 par l&rsquo;absence de pas moins de trois conditions essentielles issues de la Loi fondamentale, qui avaient \u00e9t\u00e9 soulign\u00e9es en 1992 :<\/p>\n\n<ul class=\"wp-block-list\"><li>  la demande d&rsquo;autorisation de l&rsquo;association ne pouvait pas \u00eatre attribu\u00e9e \u00e0 la volont\u00e9 des parents d&rsquo;\u00e9l\u00e8ves (une \u00e9cole primaire libre doit \u00eatre fond\u00e9e par des parents),<\/li><li>  l&#8217;empreinte confessionnelle de l&rsquo;\u00e9cole et de l&rsquo;enseignement n&rsquo;\u00e9tait pas suffisamment d\u00e9crite<\/li><li>  et une confession commune (en l&rsquo;occurrence : islamique) et surtout une communaut\u00e9 scolaire correspondante de parents, d&rsquo;enfants et d&rsquo;enseignants n&rsquo;\u00e9taient pas reconnaissables pour le tribunal.<\/li><\/ul>\n\n<p>Les arr\u00eats du Tribunal administratif f\u00e9d\u00e9ral de 1992 appliqu\u00e9s pour la premi\u00e8re fois de mani\u00e8re approfondie<\/p>\n\n<p>C&rsquo;\u00e9taient et ce sont pr\u00e9cis\u00e9ment les conditions requises pour les \u00e9coles confessionnelles et de conviction au sens de l&rsquo;article 7, paragraphe 5 de la Loi fondamentale, pr\u00e9cis\u00e9es de mani\u00e8re tr\u00e8s claire par le Tribunal administratif f\u00e9d\u00e9ral il y a 30 ans.<\/p>\n\n<p>Lorsqu&rsquo;il s&rsquo;est agi de l&rsquo;\u00e9cole primaire islamique pour Stuttgart mentionn\u00e9e ci-dessus, l&rsquo;administration scolaire de Stuttgart et le tribunal administratif ont soudain vu les choses tr\u00e8s clairement. Jusqu&rsquo;alors, l&rsquo;homog\u00e9n\u00e9it\u00e9 de la confession des parents et des \u00e9l\u00e8ves et l&#8217;empreinte confessionnelle constante de l&rsquo;\u00e9cole et de l&rsquo;enseignement auraient certainement \u00e9t\u00e9 accueillies partout de mani\u00e8re plut\u00f4t critique. Si une \u00e9cole avait pris cela au s\u00e9rieux, on lui aurait probablement reproch\u00e9 de discriminer les parents et les \u00e9l\u00e8ves qui n&rsquo;ont pas de confession ou qui en ont une, d&rsquo;enfreindre l&rsquo;article 3 de la Loi fondamentale (\"&#8230; Personne ne doit \u00eatre discrimin\u00e9 en raison &#8230; de sa foi, de ses convictions religieuses ou politiques &#8230;\") ou serait \"fondamentaliste\" et en tout cas \u00e0 rejeter.  <\/p>\n\n<p>Onze ans apr\u00e8s les jugements de 1992, la ville et le tribunal administratif ont exig\u00e9 de cette initiative de cr\u00e9ation d&rsquo;une \u00e9cole primaire islamique qu&rsquo;elle d\u00e9montre l&rsquo;homog\u00e9n\u00e9it\u00e9 de la confession et qu&rsquo;elle pr\u00e9sente une caract\u00e9ristique confessionnelle constante. En outre, les autorit\u00e9s ont exig\u00e9 la preuve que les premiers parents d&rsquo;\u00e9l\u00e8ves \u00e9taient musulmans et qu&rsquo;ils avaient finalement demand\u00e9 l&rsquo;ouverture de l&rsquo;\u00e9cole. D&rsquo;autre part, il fallait expliquer pr\u00e9cis\u00e9ment que leur confession islamique devait avoir un impact sur l&rsquo;enseignement et l&rsquo;\u00e9ducation dans l&rsquo;\u00e9cole pr\u00e9vue, et de quelle mani\u00e8re. Comme les fondateurs n&rsquo;ont pas \u00e9t\u00e9 en mesure de d\u00e9crire cela, m\u00eame apr\u00e8s coup, la cr\u00e9ation de cette \u00e9cole a d\u00fb \u00e9chouer.   <a href=\"#_ftn1\">[1]<\/a><\/p>\n\n<p>Les administrations scolaires publiques commencent \u00e0 r\u00e9agir<\/p>\n\n<p>Les plaignants islamiques se sont sentis trait\u00e9s de mani\u00e8re injuste. Leur reproche selon lequel les \u00e9coles confessionnelles chr\u00e9tiennes avaient \u00e9t\u00e9 autoris\u00e9es de mani\u00e8re g\u00e9n\u00e9reuse (parce que le respect des conditions n&rsquo;avait pas \u00e9t\u00e9 r\u00e9ellement contr\u00f4l\u00e9) \u00e9tait vrai, mais n&rsquo;a pas aid\u00e9 les plaignants dans leur proc\u00e9dure - il n&rsquo;existe pas en Allemagne de droit \u00e0 un traitement certes \u00e9gal, mais ill\u00e9gal (\"\u00e9galit\u00e9 dans l&rsquo;injustice\"). <\/p>\n\n<p>L&rsquo;issue du proc\u00e8s a progressivement conduit de nombreux L\u00e4nder \u00e0 examiner de plus pr\u00e8s les conditions exig\u00e9es par le tribunal administratif f\u00e9d\u00e9ral pour les \u00e9coles confessionnelles. De plus en plus, on exigeait d\u00e9sormais des d\u00e9clarations des parents de l&rsquo;ann\u00e9e de fondation, qui ne devaient plus seulement \u00eatre \"d&rsquo;accord\" avec le concept p\u00e9dagogique et la confession de l&rsquo;\u00e9cole, mais qui devaient aussi se ranger personnellement et explicitement derri\u00e8re la confession d\u00e9crite dans la demande d&rsquo;autorisation de l&rsquo;association scolaire. <\/p>\n\n<p>Dans le Bade-Wurtemberg, des questions (justifi\u00e9es) ont en outre \u00e9t\u00e9 pos\u00e9es sur les confessions des parents, des enfants et des enseignants, et il a souvent \u00e9t\u00e9 reproch\u00e9 aux statuts des associations scolaires pr\u00e9sent\u00e9s de ne pas indiquer clairement dans quelle mesure la participation des parents au fonctionnement de l&rsquo;\u00e9cole en tant que communaut\u00e9 confessionnelle \u00e9tait garantie. Il a \u00e9t\u00e9 demand\u00e9 \u00e0 plusieurs reprises d&rsquo;int\u00e9grer dans les statuts le passage qui ne correspond toutefois pas tout \u00e0 fait \u00e0 la jurisprudence : <em>\"Les collaborateurs p\u00e9dagogiques, les \u00e9l\u00e8ves et les parents s&rsquo;identifient \u00e0 l&rsquo;\u00e9cole, portent ensemble le profil de l&rsquo;\u00e9cole et le d\u00e9veloppent\".<\/em> Une \u00e9cole confessionnelle, qui n&rsquo;arrivait pas \u00e0 croire \u00e0 ces changements d&rsquo;avis juridiques, s&rsquo;est vu r\u00e9pondre aimablement par son autorit\u00e9 scolaire : \"Aujourd&rsquo;hui, les horloges font tic-tac un peu diff\u00e9remment qu&rsquo;\u00e0 l&rsquo;\u00e9poque\" - diff\u00e9remment qu&rsquo;avant 1992. Les jugements ont commenc\u00e9 \u00e0 produire leurs effets.  <\/p>\n\n<p>Les \u00e9coles existantes doivent remplir toutes les conditions l\u00e9gales jour apr\u00e8s jour<\/p>\n\n<p>Depuis lors, il devrait \u00eatre clair pour tous les responsables qu&rsquo;ils doivent conna\u00eetre pr\u00e9cis\u00e9ment les bases juridiques de leurs \u00e9coles confessionnelles libres et les respecter \u00e0 long terme. Cela est particuli\u00e8rement vrai pour les \u00e9coles confessionnelles du niveau primaire et du niveau d&rsquo;entr\u00e9e, car - c&rsquo;est ce que veut notre loi fondamentale - elles seraient interdites sans les conditions d&rsquo;admission pour la \"d\u00e9rogation\" de l&rsquo;article 7, paragraphe 5 de la loi fondamentale. Mais m\u00eame pour les \u00e9coles secondaires d&rsquo;une seule et m\u00eame association scolaire, il n&rsquo;y a pas beaucoup de d\u00e9rogations possibles en raison des dispositions prises dans les statuts de l&rsquo;association, la plupart du temps pour tous les types d&rsquo;\u00e9coles.  <\/p>\n\n<p>Il est \u00e9galement important de noter que cela ne concerne pas uniquement les proc\u00e9dures d&rsquo;autorisation de nouvelles \u00e9coles, mais que les \u00e9coles existantes doivent s&rsquo;y conformer quotidiennement. En effet, les conditions constitutionnelles d&rsquo;autorisation doivent \u00eatre remplies non seulement au d\u00e9but de l&rsquo;existence d&rsquo;une \u00e9cole, mais aussi sur la dur\u00e9e. <\/p>\n\n<p>Le fait que ces conditions soient r\u00e9ellement remplies est \u00e9galement important pour l&rsquo;enseignement religieux et aussi pour d&rsquo;autres domaines juridiques (par exemple les interdictions de discrimination du \u00a7 9 de l&rsquo;AGG et la participation des travailleurs selon le \u00a7 118 de la constitution de l&rsquo;entreprise) !<\/p>\n\n<p><strong>Les jugements montrent \u00e0 quel point notre Constitution est merveilleuse<\/strong><\/p>\n\n<p>La lecture des arr\u00eats vaut \u00e9galement la peine au-del\u00e0 de ces objectifs concrets, car la Cour met en lumi\u00e8re les fondements juridiques des \u00e9coles libres dans l&rsquo;article 7 de la Loi fondamentale, comme dans un manuel.<\/p>\n\n<p>Afin d&rsquo;en faciliter la lecture, l&rsquo;APDB met \u00e0 disposition le texte des arr\u00eats dans les pages suivantes, prudemment abr\u00e9g\u00e9 et accompagn\u00e9 de notes marginales explicatives.<\/p>\n\n<p>Le 19 f\u00e9vrier 1992, la Cour administrative f\u00e9d\u00e9rale a entam\u00e9 sa nouvelle jurisprudence avec son jugement sur l&rsquo;autorisation d&rsquo;une \u00e9cole de conviction (r\u00e9f\u00e9rence 6 C <strong>5<\/strong>.91). Par un autre jugement du m\u00eame jour (r\u00e9f\u00e9rence 6 C <strong>3<\/strong>.91), l&rsquo;\u00e9cole de Hambourg a \u00e9t\u00e9 autoris\u00e9e en tant qu&rsquo;\u00e9cole confessionnelle. <\/p>\n\n<p>\u00c9tant donn\u00e9 que les notions de Weltanschauung et de Bekenntnis ne se distinguent juridiquement que par le fait que la Bekenntnis, contrairement \u00e0 la Weltanschauung, comporte une r\u00e9f\u00e9rence \u00e0 Dieu, le m\u00eame droit s&rsquo;applique donc en grande partie aux deux types d&rsquo;\u00e9coles, comme c&rsquo;est le cas pour les \u00e9coles \u00e0 profil p\u00e9dagogique particulier.<\/p>\n\n<p>Les \u00e9coles confessionnelles doivent \u00eatre diff\u00e9rentes, mais \"\u00e9quivalentes<\/p>\n\n<p>Les \"principes directeurs\" des arr\u00eats r\u00e9sument les principales r\u00e8gles applicables aux \u00e9coles confessionnelles.<\/p>\n\n<p>Les exigences du tribunal,<\/p>\n\n<ul class=\"wp-block-list\"><li>  que la confession des parents est d\u00e9terminante,<\/li><li>qu&rsquo;ils doivent avoir une confession de foi commune (\"homog\u00e9n\u00e9it\u00e9 de la confession de foi des parents, des \u00e9l\u00e8ves et des enseignants\"),<\/li><li>que l&rsquo;\u00e9cole et l&rsquo;enseignement doivent \u00eatre marqu\u00e9s en permanence par cette profession de foi<\/li><li>et qu&rsquo;une communaut\u00e9 portant cette confession de foi doit \u00eatre garantie avec un caract\u00e8re obligatoire (association scolaire en tant que garante de la confession de foi),<\/li><\/ul>\n\n<p>doit \u00eatre connu et imp\u00e9rativement respect\u00e9 dans chaque \u00e9cole.<\/p>\n\n<p>Inversement, nous pouvons \u00eatre reconnaissants au tribunal administratif f\u00e9d\u00e9ral d&rsquo;avoir interpr\u00e9t\u00e9 de mani\u00e8re tr\u00e8s large la notion d&rsquo;objectifs p\u00e9dagogiques pour l&rsquo;exigence d&rsquo;\u00e9quivalence de l&rsquo;article 7, paragraphe 4 de la Loi fondamentale : Elle englobe aussi bien les objectifs \u00e9ducatifs que la qualification \u00e0 transmettre.<\/p>\n\n<p>Une \u00e9cole confessionnelle ne peut pas, en raison de son caract\u00e8re confessionnel, \u00eatre inf\u00e9rieure aux \u00e9coles publiques correspondantes en termes d&rsquo;objectifs \u00e9ducatifs ou de qualifications \u00e0 transmettre, comme l&rsquo;a clairement \u00e9tabli le tribunal administratif f\u00e9d\u00e9ral (plus personne n&rsquo;osera aujourd&rsquo;hui faire cette insinuation au gouvernement du Land - au contraire, les maires de tout le pays louent la qualit\u00e9 des \u00e9coles confessionnelles chr\u00e9tiennes libres). L&rsquo;influence confessionnelle ne doit jamais avoir pour cons\u00e9quence des \"d\u00e9ficits\" en ce qui concerne les biens \u00e9ducatifs g\u00e9n\u00e9raux ou la mani\u00e8re dont la mati\u00e8re est enseign\u00e9e doit conduire \u00e0 un parti pris de la part des \u00e9l\u00e8ves (pas de \"d\u00e9formations\"). <\/p>\n\n<p>Objectifs \u00e9ducatifs propres \u00e0 une \u00e9cole confessionnelle<\/p>\n\n<p>Enfin, le tribunal a pr\u00e9cis\u00e9 le droit des \u00e9coles de substitution de <em>\"poursuivre, outre les objectifs d&rsquo;enseignement fix\u00e9s par l&rsquo;\u00c9tat, y compris les objectifs \u00e9ducatifs, d&rsquo;autres objectifs \u00e9ducatifs qui ne sont en tout cas pas en contradiction avec les objectifs \u00e9ducatifs de l&rsquo;\u00c9tat, d&rsquo;autant plus que les objectifs \u00e9ducatifs de l&rsquo;\u00c9tat laissent typiquement de la place pour un remplissage du contenu dans l&rsquo;enseignement concret\".<\/em><\/p>\n\n<p>Il s&rsquo;est pench\u00e9 de mani\u00e8re approfondie sur l&rsquo;objectif \u00e9ducatif g\u00e9n\u00e9ral obligatoire de l&rsquo;\u00c9tat, qui consiste \u00e0 \"<em>aider les \u00e9l\u00e8ves \u00e0 s&rsquo;orienter de mani\u00e8re autonome et \u00e0 mener leur vie sous leur propre responsabilit\u00e9, ainsi qu&rsquo;\u00e0 d\u00e9velopper et \u00e0 affirmer leur capacit\u00e9 individuelle de perception et de jugement<\/em>\".<\/p>\n\n<p>C&rsquo;est pr\u00e9cis\u00e9ment ce que nous voulons faire si nous voulons permettre aux jeunes de vivre leur foi en J\u00e9sus dans le monde.<\/p>\n\n<p>L&rsquo;importance du principe de tol\u00e9rance pour les \u00e9coles confessionnelles<\/p>\n\n<p>Parmi les objectifs \u00e9ducatifs, une attention particuli\u00e8re a \u00e9t\u00e9 accord\u00e9e au principe de tol\u00e9rance. La motivation du jugement \u00e0 ce sujet a \u00e9t\u00e9 le seul point sur lequel les jugements de 1992 du tribunal administratif f\u00e9d\u00e9ral ont \u00e9t\u00e9 critiqu\u00e9s par les juristes la\u00efques. Il n&rsquo;exige <em>, \"dans le cadre d&rsquo;une application conforme \u00e0 la Constitution, sp\u00e9cialement pour les \u00e9coles confessionnelles, que le degr\u00e9 de tol\u00e9rance \u00e0 l&rsquo;\u00e9gard d&rsquo;autres convictions divergentes\" qui est \"une condition pr\u00e9alable \u00e0 une discussion ouverte avec d&rsquo;autres convictions<\/em>\".  <\/p>\n\n<p>Les phrases suivantes, essentielles pour les \u00e9coles, suivent :  <em>\"Toute \"profession de foi\" est, de par sa nature, destin\u00e9e \u00e0 \u00eatre profess\u00e9e et promue par la conviction de la justesse de ses propres id\u00e9es et appr\u00e9ciations. Ainsi, l&rsquo;article 7, paragraphe 4, troisi\u00e8me phrase, de la Loi fondamentale consid\u00e8re comme allant de soi et donc admissible un objectif \u00e9ducatif faisant la promotion de la confession de foi. <\/em>\"<a href=\"#_ftn2\">[2]<\/a><em>.<\/em><\/p>\n\n<p>Ainsi, la motivation du jugement est devenue, sur ce point \u00e9galement, une interpr\u00e9tation juridique pr\u00e9cieuse pour les \u00e9coles confessionnelles.<\/p>\n\n<p>M\u00eame un automobiliste qui n&rsquo;est pas juriste peut \u00eatre tenu de conna\u00eetre le code de la route.<\/p>\n\n<p>Les jugements pourraient donner l&rsquo;impression que l&rsquo;examen de ces questions juridiques exige des comp\u00e9tences juridiques que l&rsquo;on ne peut pas exiger des fondateurs d&rsquo;\u00e9coles, des conseils d&rsquo;administration, des directeurs d&rsquo;\u00e9coles et des enseignants ind\u00e9pendants&#8230;<\/p>\n\n<p>Si, on peut l&rsquo;exiger !<\/p>\n\n<p>Les automobilistes, les ramoneurs et les bouchers ne sont pas non plus des juristes, et ils doivent pourtant tous conna\u00eetre et respecter scrupuleusement le code de la route, les r\u00e8gles de protection contre les incendies ou les r\u00e8gles d&rsquo;hygi\u00e8ne qui leur sont applicables !<\/p>\n\n<p>Les organes de l&rsquo;association et les collaborateurs doivent faire face \u00e0 ces exigences s&rsquo;ils ne veulent pas mettre en p\u00e9ril la raison d&rsquo;\u00eatre de leurs \u00e9coles au caract\u00e8re particulier.<\/p>\n\n<p>La Cour administrative f\u00e9d\u00e9rale tire actuellement les cons\u00e9quences de ses arr\u00eats de 1992, m\u00eame pour l&rsquo;enseignement religieux<\/p>\n\n<p>30 ans, c&rsquo;est long - est-ce qu&rsquo;une ou deux g\u00e9n\u00e9rations de juges plus tard, le Tribunal administratif f\u00e9d\u00e9ral jugerait encore aujourd&rsquo;hui de la m\u00eame mani\u00e8re qu&rsquo;\u00e0 l&rsquo;\u00e9poque ??? C&rsquo;est une question l\u00e9gitime, car la jurisprudence \"\u00e9volue\", c&rsquo;est-\u00e0-dire qu&rsquo;elle change souvent.<\/p>\n\n<p>Mais non - le Tribunal administratif f\u00e9d\u00e9ral a poursuivi sa jurisprudence avec pr\u00e9cision en rendant une d\u00e9cision sur l&rsquo;enseignement religieux en 20193 ! Par cette d\u00e9cision, la Cour a rejet\u00e9 une proc\u00e9dure de r\u00e9vision engag\u00e9e par le gouvernement du Land de Bade-Wurtemberg contre un jugement qui lui \u00e9tait d\u00e9favorable, parce qu&rsquo;il avait d\u00e9j\u00e0 \u00e9t\u00e9 jug\u00e9 \u00e0 ce sujet en 1992 et que la Cour, m\u00eame avec des juges plus jeunes, s&rsquo;y tient express\u00e9ment, voire m\u00eame avec insistance. <\/p>\n\n<p>L&rsquo;article 7, paragraphe 3, de la Grundgesetz (loi fondamentale) n&rsquo;impose pas l&rsquo;enseignement de la religion comme mati\u00e8re aux \u00e9coles de substitution.<\/p>\n\n<p>En raison de cette justification remarquable, nous imprimons \u00e9galement la d\u00e9cision du tribunal administratif f\u00e9d\u00e9ral de 2019 concernant l&rsquo;enseignement religieux - bien qu&rsquo;elle n&rsquo;ait de signification directe pour aucune des \u00e9coles de VEBS, car le jugement ne concerne que les \u00e9coles de remplacement qui ne sont que des \u00e9coles de remplacement \"autoris\u00e9es\" selon la notion juridique du Bade-Wurtemberg (en Rh\u00e9nanie-du-Nord-Westphalie, on parle d'\"autorisation provisoire\") ; pour ces \u00e9coles, la d\u00e9cision s&rsquo;applique toutefois \u00e0 l&rsquo;ensemble du pays. Toutes les \u00e9coles de la VEBS sont cependant des Ersatzschulen \"reconnues\" (en NRW, des Ersatzschulen \"autoris\u00e9es\") ou aspirent \u00e0 le devenir dans les plus brefs d\u00e9lais apr\u00e8s leur cr\u00e9ation. <\/p>\n\n<p>Mais une proc\u00e9dure administrative correspondante est \u00e9galement en cours pour les \u00e9coles de remplacement \"reconnues\", toujours dans le Bade-Wurtemberg. Actuellement, le plaignant attend une date de proc\u00e8s en deuxi\u00e8me instance - ensuite, le recours au tribunal administratif f\u00e9d\u00e9ral est certain, un jugement d\u00e9finitif y sera rendu d&rsquo;ici le milieu de la d\u00e9cennie. <\/p>\n\n<p>Dans la d\u00e9cision de 2019, la Cour administrative f\u00e9d\u00e9rale a confirm\u00e9 qu&rsquo;une \u00e9cole de substitution agr\u00e9\u00e9e n&rsquo;est pas tenue de proposer la mati\u00e8re \"religion\" enseign\u00e9e par l&rsquo;\u00c9glise nationale. L&rsquo;article 7, paragraphe 3, de la Loi fondamentale<a href=\"#_ftn3\">[3]<\/a> ne s&rsquo;applique pas aux \u00e9coles de substitution, ni directement ni indirectement, car l&rsquo;\u00c9tat ne peut pas nier l'\"\u00e9quivalence\" de ces \u00e9coles en raison de l&rsquo;absence de cours de religion. <\/p>\n\n<p>Les \u00e9coles confessionnelles peuvent se r\u00e9jouir de la ligne directrice de l&rsquo;arr\u00eat \u00e0 ce sujet : \"<em>Une \u00e9cole priv\u00e9e de substitution n&rsquo;est pas en retard sur les \u00e9coles publiques dans ses objectifs d&rsquo;enseignement au sens de l&rsquo;article 7, paragraphe 4, phrase 3 de la Loi fondamentale, parce qu&rsquo;elle ne propose pas de cours de religion<\/em>\" - il s&rsquo;agit ici d&rsquo;un \"cours de religion\" en accord avec les principes et sous le contr\u00f4le de l&rsquo;\u00c9glise protestante nationale (par exemple, obligation de vocation !).<\/p>\n\n<p>En outre, le tribunal a \u00e9tay\u00e9 la constatation cit\u00e9e en pr\u00e9cisant que les Ersatzschulen <em>\"ne peuvent \u00eatre tenues de remplir d&rsquo;autres conditions d&rsquo;autorisation que celles \u00e9num\u00e9r\u00e9es \u00e0 l&rsquo;article 7, paragraphe 4, troisi\u00e8me phrase, de la Loi fondamentale\", \"ni par le droit du Land, ni par une certaine conception de la pratique d&rsquo;autorisation des autorit\u00e9s scolaires\"<\/em>.<\/p>\n\n<p>Il s&rsquo;est appuy\u00e9 pour cela sur deux arr\u00eats de la Cour constitutionnelle f\u00e9d\u00e9rale de 1969 et de 1987 : \"<em>Le domaine soustrait \u00e0 l&rsquo;influence de l&rsquo;\u00c9tat se caract\u00e9rise par le fait que l&rsquo;enseignement dispens\u00e9 dans l&rsquo;\u00e9cole priv\u00e9e est empreint de responsabilit\u00e9 et con\u00e7u de mani\u00e8re autonome, en particulier dans la mesure o\u00f9 il concerne les objectifs \u00e9ducatifs, la base id\u00e9ologique, la m\u00e9thode d&rsquo;enseignement et les contenus d&rsquo;enseignement\".<\/em><\/p>\n\n<p>L&rsquo;enseignement de la religion n&rsquo;est pas n\u00e9cessaire - en revanche, obligation d'\"impr\u00e9gner\" toutes les mati\u00e8res de questions \u00e9thiques !<\/p>\n\n<p>La d\u00e9cision de 2019 accorde une grande libert\u00e9 aux \u00e9coles libres pour l&rsquo;organisation de l&rsquo;enseignement religieux :  <em>\"Pour le minimum requis par la Constitution en mati\u00e8re de transmission des valeurs \u00e0 l&rsquo;\u00e9cole, il n&rsquo;est pas n\u00e9cessaire d&rsquo;enseigner la religion, ni m\u00eame une mati\u00e8re particuli\u00e8re. D&rsquo;autres mati\u00e8res, telles que l&rsquo;allemand ou l&rsquo;\u00e9ducation civique, se pr\u00eatent \u00e9galement au traitement de questions \u00e9thiques. <\/em>.\"<\/p>\n\n<p>Le tribunal a express\u00e9ment indiqu\u00e9 qu&rsquo;en raison de l&rsquo;objet du litige, sa d\u00e9cision ne s&rsquo;applique qu&rsquo;aux proc\u00e9dures d&rsquo;autorisation et non pas automatiquement \u00e0 la reconnaissance des \u00e9coles confessionnelles. C&rsquo;est pourquoi le minist\u00e8re de l&rsquo;\u00c9ducation du Bade-Wurtemberg (qui a perdu le proc\u00e8s) a rapidement r\u00e9agi \u00e0 la d\u00e9cision : \"<em>Il convient de dissocier de cette question celle de l&rsquo;octroi du statut d&rsquo;\u00e9cole de substitution <u>reconnue<\/u>, qui conf\u00e8re \u00e0 l&rsquo;\u00e9cole le droit d&rsquo;organiser des examens et de d\u00e9livrer des certificats conform\u00e9ment aux dispositions g\u00e9n\u00e9rales applicables aux \u00e9coles publiques<\/em>\", et a d\u00e9cr\u00e9t\u00e9 pour le Bade-Wurtemberg : <em>\"Il convient de continuer \u00e0 exiger des \u00e9coles de substitution reconnues qu&rsquo;elles proposent et dispensent un enseignement religieux \"4.<\/em> <\/p>\n\n<p>Nous ne sommes pas les seuls \u00e0 douter de la l\u00e9galit\u00e9 de cette mesure - la Cour constitutionnelle allemande rendra son jugement d\u00e9finitif dans quelques ann\u00e9es !<\/p>\n\n<p>En Allemagne, les \u00e9coles confessionnelles chr\u00e9tiennes ont un merveilleux fondement juridique<\/p>\n\n<p>Nous ne serons jamais assez reconnaissants pour ces bases juridiques des \u00e9coles chr\u00e9tiennes confessionnelles dont nous b\u00e9n\u00e9ficions en Allemagne et qui nous sont envi\u00e9es par les \u00e9coles chr\u00e9tiennes, m\u00eame dans les pays voisins imm\u00e9diats.<\/p>\n\n<p>C&rsquo;est pourquoi nous avons aussi le devoir, en tant que bons administrateurs, non seulement de conna\u00eetre ces fondements, mais aussi d&rsquo;en reconna\u00eetre l&rsquo;utilit\u00e9, notamment pour les ann\u00e9es plus tumultueuses. Cela signifie avant tout de prendre en consid\u00e9ration les fondements <strong>spirituels<\/strong> de nos \u00e9coles, exig\u00e9s par la loi, et de les utiliser de mani\u00e8re globale pour la vie quotidienne (administration et p\u00e9dagogie). <\/p>\n\n<p>Il ne s&rsquo;agit pas d&rsquo;une quelconque \"organisation\" pour r\u00e9pondre sommairement \u00e0 des exigences l\u00e9gales. Non, il s&rsquo;agit, tout \u00e0 fait dans l&rsquo;esprit des fondateurs de l&rsquo;\u00e9cole et conform\u00e9ment \u00e0 nos pr\u00e9occupations spirituelles, de mettre en \u0153uvre la communaut\u00e9 de confession de foi exig\u00e9e et l&rsquo;impr\u00e9gnation confessionnelle de l&rsquo;enseignement et du quotidien scolaire que nous souhaitons, de mani\u00e8re \u00e0 ce que nos \u00e9coles - les \u00e9coles de Dieu - puissent bien fonctionner \u00e0 long terme. <\/p>\n\n<p>19 f\u00e9vrier 2022<\/p>\n\n<p>Prof. Dr Wolfgang Stock<\/p>\n\n<hr class=\"wp-block-separator\"\/>\n\n<p>[<a href=\"#_ftnref1\">1]<\/a> Depuis lors, des \u00e9coles islamiques ont \u00e9t\u00e9 cr\u00e9\u00e9es avec succ\u00e8s.<\/p>\n\n<p>[<a href=\"#_ftnref2\">2]<\/a> La citation compliqu\u00e9e de l&rsquo;arr\u00eat est la suivante : \"Ainsi, l&rsquo;article 7, paragraphe 4, phrase 3 de la Loi fondamentale non seulement n&rsquo;exclut pas un tel objectif \u00e9ducatif dans le cas d&rsquo;une \u00e9cole priv\u00e9e confessionnelle, mais le pr\u00e9suppose \u00e0 l&rsquo;inverse comme allant de soi et donc admissible\". (Ici, aucun des deux \"pas\" ne doit \u00eatre omis, comme cela - inversant l&rsquo;affirmation en son contraire - est malheureusement d\u00e9j\u00e0 arriv\u00e9 dans la litt\u00e9rature juridique).<\/p>\n\n<p><a href=\"#_ftnref3\">[3]<\/a> <em>\"L&rsquo;enseignement religieux est une mati\u00e8re ordinaire dans les \u00e9coles <u>publiques<\/u>, \u00e0 l&rsquo;exception des \u00e9coles non confessionnelles. Sans pr\u00e9judice du droit de contr\u00f4le de l&rsquo;\u00c9tat, l&rsquo;enseignement religieux est dispens\u00e9 <a>en conformit\u00e9 avec les principes des communaut\u00e9s religieuses <\/a>\". <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il y a 30 ans, le tribunal administratif f\u00e9d\u00e9ral a \u00e9crit l&rsquo;histoire de l&rsquo;\u00e9cole : Il a contraint le Land de Hambourg \u00e0 autoriser une \u00e9cole confessionnelle protestante libre (les actuelles August-Hermann-Francke-Schulen).  <\/p>\n","protected":false},"author":2,"featured_media":39701,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[295],"tags":[],"class_list":["post-40947","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-page-daccueil"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les \u00e9coles confessionnelles libres - un droit fondamental, si les conditions sont remplies et le restent ! - VEBS e.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vebs.de\/fr\/les-ecoles-confessionnelles-libres-un-droit-fondamental-si-les-conditions-sont-remplies-et-le-restent\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les \u00e9coles confessionnelles libres - un droit fondamental, si les conditions sont remplies et le restent ! - VEBS e.V.\" \/>\n<meta property=\"og:description\" content=\"Il y a 30 ans, le tribunal administratif f\u00e9d\u00e9ral a \u00e9crit l&#039;histoire de l&#039;\u00e9cole : Il a contraint le Land de Hambourg \u00e0 autoriser une \u00e9cole confessionnelle protestante libre (les actuelles August-Hermann-Francke-Schulen).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vebs.de\/fr\/les-ecoles-confessionnelles-libres-un-droit-fondamental-si-les-conditions-sont-remplies-et-le-restent\/\" \/>\n<meta property=\"og:site_name\" content=\"VEBS e.V.\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-21T13:21:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-26T06:42:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vebs.de\/wp-content\/uploads\/2022\/03\/Broschu\u0308re-foto_Zeichenfla\u0308che-1_Zeichenfla\u0308che-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1381\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Norman Kronenwett\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Norman Kronenwett\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"19 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.vebs.de\/fr\/les-ecoles-confessionnelles-libres-un-droit-fondamental-si-les-conditions-sont-remplies-et-le-restent\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.vebs.de\/fr\/les-ecoles-confessionnelles-libres-un-droit-fondamental-si-les-conditions-sont-remplies-et-le-restent\/\"},\"author\":{\"name\":\"Norman Kronenwett\",\"@id\":\"https:\/\/www.vebs.de\/fr\/#\/schema\/person\/2c2d36384cb9c56b0b47223c61f35512\"},\"headline\":\"Les \u00e9coles confessionnelles libres - un droit fondamental, si les conditions sont remplies et le restent !\",\"datePublished\":\"2022-03-21T13:21:52+00:00\",\"dateModified\":\"2025-06-26T06:42:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.vebs.de\/fr\/les-ecoles-confessionnelles-libres-un-droit-fondamental-si-les-conditions-sont-remplies-et-le-restent\/\"},\"wordCount\":4110,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.vebs.de\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.vebs.de\/fr\/les-ecoles-confessionnelles-libres-un-droit-fondamental-si-les-conditions-sont-remplies-et-le-restent\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.vebs.de\/wp-content\/uploads\/2022\/03\/Broschu\u0308re-foto_Zeichenfla\u0308che-1_Zeichenfla\u0308che-1.jpg\",\"articleSection\":[\"Page d'accueil\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.vebs.de\/fr\/les-ecoles-confessionnelles-libres-un-droit-fondamental-si-les-conditions-sont-remplies-et-le-restent\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.vebs.de\/fr\/les-ecoles-confessionnelles-libres-un-droit-fondamental-si-les-conditions-sont-remplies-et-le-restent\/\",\"url\":\"https:\/\/www.vebs.de\/fr\/les-ecoles-confessionnelles-libres-un-droit-fondamental-si-les-conditions-sont-remplies-et-le-restent\/\",\"name\":\"Les \u00e9coles confessionnelles libres - un droit fondamental, si les conditions sont remplies et le restent ! - VEBS e.V.\",\"isPartOf\":{\"@id\":\"https:\/\/www.vebs.de\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.vebs.de\/fr\/les-ecoles-confessionnelles-libres-un-droit-fondamental-si-les-conditions-sont-remplies-et-le-restent\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.vebs.de\/fr\/les-ecoles-confessionnelles-libres-un-droit-fondamental-si-les-conditions-sont-remplies-et-le-restent\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.vebs.de\/wp-content\/uploads\/2022\/03\/Broschu\u0308re-foto_Zeichenfla\u0308che-1_Zeichenfla\u0308che-1.jpg\",\"datePublished\":\"2022-03-21T13:21:52+00:00\",\"dateModified\":\"2025-06-26T06:42:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.vebs.de\/fr\/les-ecoles-confessionnelles-libres-un-droit-fondamental-si-les-conditions-sont-remplies-et-le-restent\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.vebs.de\/fr\/les-ecoles-confessionnelles-libres-un-droit-fondamental-si-les-conditions-sont-remplies-et-le-restent\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.vebs.de\/fr\/les-ecoles-confessionnelles-libres-un-droit-fondamental-si-les-conditions-sont-remplies-et-le-restent\/#primaryimage\",\"url\":\"https:\/\/www.vebs.de\/wp-content\/uploads\/2022\/03\/Broschu\u0308re-foto_Zeichenfla\u0308che-1_Zeichenfla\u0308che-1.jpg\",\"contentUrl\":\"https:\/\/www.vebs.de\/wp-content\/uploads\/2022\/03\/Broschu\u0308re-foto_Zeichenfla\u0308che-1_Zeichenfla\u0308che-1.jpg\",\"width\":1381,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.vebs.de\/fr\/les-ecoles-confessionnelles-libres-un-droit-fondamental-si-les-conditions-sont-remplies-et-le-restent\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.vebs.de\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les \u00e9coles confessionnelles libres &#8211; un droit fondamental, si les conditions sont remplies et le restent !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.vebs.de\/fr\/#website\",\"url\":\"https:\/\/www.vebs.de\/fr\/\",\"name\":\"VEBS e.V.\",\"description\":\"Verband Evangelischer Bekenntnisschulen e.V.\",\"publisher\":{\"@id\":\"https:\/\/www.vebs.de\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.vebs.de\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.vebs.de\/fr\/#organization\",\"name\":\"Verband Evangelischer Bekenntnisschulen e.V. (VEBS)\",\"url\":\"https:\/\/www.vebs.de\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.vebs.de\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.vebs.de\/wp-content\/uploads\/2021\/03\/vebs-Logo-v2_rot_300x177.png\",\"contentUrl\":\"https:\/\/www.vebs.de\/wp-content\/uploads\/2021\/03\/vebs-Logo-v2_rot_300x177.png\",\"width\":300,\"height\":177,\"caption\":\"Verband Evangelischer Bekenntnisschulen e.V. (VEBS)\"},\"image\":{\"@id\":\"https:\/\/www.vebs.de\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.vebs.de\/fr\/#\/schema\/person\/2c2d36384cb9c56b0b47223c61f35512\",\"name\":\"Norman Kronenwett\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.vebs.de\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1511a118cf7ccb954d109f2321b19631ccfe59681fe02aad730617e0a0ff49c2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1511a118cf7ccb954d109f2321b19631ccfe59681fe02aad730617e0a0ff49c2?s=96&d=mm&r=g\",\"caption\":\"Norman Kronenwett\"},\"url\":\"https:\/\/www.vebs.de\/fr\/author\/norman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les \u00e9coles confessionnelles libres - un droit fondamental, si les conditions sont remplies et le restent ! - VEBS e.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vebs.de\/fr\/les-ecoles-confessionnelles-libres-un-droit-fondamental-si-les-conditions-sont-remplies-et-le-restent\/","og_locale":"fr_FR","og_type":"article","og_title":"Les \u00e9coles confessionnelles libres - un droit fondamental, si les conditions sont remplies et le restent ! - VEBS e.V.","og_description":"Il y a 30 ans, le tribunal administratif f\u00e9d\u00e9ral a \u00e9crit l'histoire de l'\u00e9cole : Il a contraint le Land de Hambourg \u00e0 autoriser une \u00e9cole confessionnelle protestante libre (les actuelles August-Hermann-Francke-Schulen).","og_url":"https:\/\/www.vebs.de\/fr\/les-ecoles-confessionnelles-libres-un-droit-fondamental-si-les-conditions-sont-remplies-et-le-restent\/","og_site_name":"VEBS e.V.","article_published_time":"2022-03-21T13:21:52+00:00","article_modified_time":"2025-06-26T06:42:02+00:00","og_image":[{"width":1381,"height":1024,"url":"https:\/\/www.vebs.de\/wp-content\/uploads\/2022\/03\/Broschu\u0308re-foto_Zeichenfla\u0308che-1_Zeichenfla\u0308che-1.jpg","type":"image\/jpeg"}],"author":"Norman Kronenwett","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Norman Kronenwett","Est. reading time":"19 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vebs.de\/fr\/les-ecoles-confessionnelles-libres-un-droit-fondamental-si-les-conditions-sont-remplies-et-le-restent\/#article","isPartOf":{"@id":"https:\/\/www.vebs.de\/fr\/les-ecoles-confessionnelles-libres-un-droit-fondamental-si-les-conditions-sont-remplies-et-le-restent\/"},"author":{"name":"Norman Kronenwett","@id":"https:\/\/www.vebs.de\/fr\/#\/schema\/person\/2c2d36384cb9c56b0b47223c61f35512"},"headline":"Les \u00e9coles confessionnelles libres - un droit fondamental, si les conditions sont remplies et le restent !","datePublished":"2022-03-21T13:21:52+00:00","dateModified":"2025-06-26T06:42:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vebs.de\/fr\/les-ecoles-confessionnelles-libres-un-droit-fondamental-si-les-conditions-sont-remplies-et-le-restent\/"},"wordCount":4110,"commentCount":0,"publisher":{"@id":"https:\/\/www.vebs.de\/fr\/#organization"},"image":{"@id":"https:\/\/www.vebs.de\/fr\/les-ecoles-confessionnelles-libres-un-droit-fondamental-si-les-conditions-sont-remplies-et-le-restent\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vebs.de\/wp-content\/uploads\/2022\/03\/Broschu\u0308re-foto_Zeichenfla\u0308che-1_Zeichenfla\u0308che-1.jpg","articleSection":["Page d'accueil"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.vebs.de\/fr\/les-ecoles-confessionnelles-libres-un-droit-fondamental-si-les-conditions-sont-remplies-et-le-restent\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.vebs.de\/fr\/les-ecoles-confessionnelles-libres-un-droit-fondamental-si-les-conditions-sont-remplies-et-le-restent\/","url":"https:\/\/www.vebs.de\/fr\/les-ecoles-confessionnelles-libres-un-droit-fondamental-si-les-conditions-sont-remplies-et-le-restent\/","name":"Les \u00e9coles confessionnelles libres - un droit fondamental, si les conditions sont remplies et le restent ! - VEBS e.V.","isPartOf":{"@id":"https:\/\/www.vebs.de\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vebs.de\/fr\/les-ecoles-confessionnelles-libres-un-droit-fondamental-si-les-conditions-sont-remplies-et-le-restent\/#primaryimage"},"image":{"@id":"https:\/\/www.vebs.de\/fr\/les-ecoles-confessionnelles-libres-un-droit-fondamental-si-les-conditions-sont-remplies-et-le-restent\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vebs.de\/wp-content\/uploads\/2022\/03\/Broschu\u0308re-foto_Zeichenfla\u0308che-1_Zeichenfla\u0308che-1.jpg","datePublished":"2022-03-21T13:21:52+00:00","dateModified":"2025-06-26T06:42:02+00:00","breadcrumb":{"@id":"https:\/\/www.vebs.de\/fr\/les-ecoles-confessionnelles-libres-un-droit-fondamental-si-les-conditions-sont-remplies-et-le-restent\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vebs.de\/fr\/les-ecoles-confessionnelles-libres-un-droit-fondamental-si-les-conditions-sont-remplies-et-le-restent\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vebs.de\/fr\/les-ecoles-confessionnelles-libres-un-droit-fondamental-si-les-conditions-sont-remplies-et-le-restent\/#primaryimage","url":"https:\/\/www.vebs.de\/wp-content\/uploads\/2022\/03\/Broschu\u0308re-foto_Zeichenfla\u0308che-1_Zeichenfla\u0308che-1.jpg","contentUrl":"https:\/\/www.vebs.de\/wp-content\/uploads\/2022\/03\/Broschu\u0308re-foto_Zeichenfla\u0308che-1_Zeichenfla\u0308che-1.jpg","width":1381,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/www.vebs.de\/fr\/les-ecoles-confessionnelles-libres-un-droit-fondamental-si-les-conditions-sont-remplies-et-le-restent\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vebs.de\/fr\/"},{"@type":"ListItem","position":2,"name":"Les \u00e9coles confessionnelles libres &#8211; un droit fondamental, si les conditions sont remplies et le restent !"}]},{"@type":"WebSite","@id":"https:\/\/www.vebs.de\/fr\/#website","url":"https:\/\/www.vebs.de\/fr\/","name":"VEBS e.V.","description":"Verband Evangelischer Bekenntnisschulen e.V.","publisher":{"@id":"https:\/\/www.vebs.de\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vebs.de\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vebs.de\/fr\/#organization","name":"Verband Evangelischer Bekenntnisschulen e.V. (VEBS)","url":"https:\/\/www.vebs.de\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vebs.de\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.vebs.de\/wp-content\/uploads\/2021\/03\/vebs-Logo-v2_rot_300x177.png","contentUrl":"https:\/\/www.vebs.de\/wp-content\/uploads\/2021\/03\/vebs-Logo-v2_rot_300x177.png","width":300,"height":177,"caption":"Verband Evangelischer Bekenntnisschulen e.V. (VEBS)"},"image":{"@id":"https:\/\/www.vebs.de\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.vebs.de\/fr\/#\/schema\/person\/2c2d36384cb9c56b0b47223c61f35512","name":"Norman Kronenwett","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vebs.de\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1511a118cf7ccb954d109f2321b19631ccfe59681fe02aad730617e0a0ff49c2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1511a118cf7ccb954d109f2321b19631ccfe59681fe02aad730617e0a0ff49c2?s=96&d=mm&r=g","caption":"Norman Kronenwett"},"url":"https:\/\/www.vebs.de\/fr\/author\/norman\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vebs.de\/fr\/wp-json\/wp\/v2\/posts\/40947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vebs.de\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vebs.de\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vebs.de\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vebs.de\/fr\/wp-json\/wp\/v2\/comments?post=40947"}],"version-history":[{"count":1,"href":"https:\/\/www.vebs.de\/fr\/wp-json\/wp\/v2\/posts\/40947\/revisions"}],"predecessor-version":[{"id":40949,"href":"https:\/\/www.vebs.de\/fr\/wp-json\/wp\/v2\/posts\/40947\/revisions\/40949"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vebs.de\/fr\/wp-json\/wp\/v2\/media\/39701"}],"wp:attachment":[{"href":"https:\/\/www.vebs.de\/fr\/wp-json\/wp\/v2\/media?parent=40947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vebs.de\/fr\/wp-json\/wp\/v2\/categories?post=40947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vebs.de\/fr\/wp-json\/wp\/v2\/tags?post=40947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}