{"id":40923,"date":"2022-04-20T09:17:00","date_gmt":"2022-04-20T07:17:00","guid":{"rendered":"https:\/\/www.vebs.de\/ddps-une-clarte-spirituelle-qui-nempeche-pas-la-diversite\/"},"modified":"2025-09-17T14:48:29","modified_gmt":"2025-09-17T12:48:29","slug":"vebs-geistlich-klar-und-trotzdem-vielfaeltig","status":"publish","type":"post","link":"https:\/\/www.vebs.de\/fr\/vebs-geistlich-klar-und-trotzdem-vielfaeltig\/","title":{"rendered":"DDPS : une clart\u00e9 spirituelle qui n&#8217;emp\u00eache pas la diversit\u00e9"},"content":{"rendered":"\n<p>En fait, les quatre premi\u00e8res fondations d&rsquo;\u00e9coles \u00e9vang\u00e9liques libres en R\u00e9publique f\u00e9d\u00e9rale d&rsquo;Allemagne (Reutlingen, Br\u00eame, Giessen, Francfort) n&rsquo;\u00e9taient (et ne sont) en aucune mani\u00e8re marqu\u00e9es par l&rsquo;Allemagne russe. Ils ne se sont pas non plus appel\u00e9s et ne s&rsquo;appellent pas \"\u00e9vang\u00e9liques\" et trois des quatre fondations ne se trouvaient certainement pas dans la \"Bible Belt\". (Ces quatre \u00e9coles ont jou\u00e9 un r\u00f4le absolument d\u00e9terminant au sein de l&rsquo;association nationale informelle AEBS (jusqu&rsquo;en 2006), avec un droit de veto respectif).<br\/>De m\u00eame, les fondations suivantes dans les m\u00e9gapoles de Berlin (1989, aujourd&rsquo;hui plus de 1.000 enfants et adolescents) et de Hambourg (1992) n&rsquo;avaient ni origine allemande russe ni origine pi\u00e9tiste. Au contraire, dans les grandes villes, il a \u00e9t\u00e9 possible de r\u00e9pondre \u00e0 l&rsquo;exigence de l&rsquo;article 7, paragraphe 5, de la Loi fondamentale, de trouver suffisamment de chr\u00e9tiens pour pouvoir lancer pour leurs filles et fils une \u00e9cole avec une confession de foi commune sur la \"base commune de la foi\" de l&rsquo;Alliance \u00e9vang\u00e9lique.   <\/p>\n\n<p>Les \u00e9coles fond\u00e9es peu apr\u00e8s, \u00e9galement par des parents protestants, \u00e0 L\u00f6rrach (1989, aujourd&rsquo;hui 2.350 enfants et adolescents, actuellement la plus grande \u00e9cole priv\u00e9e du Bade-Wurtemberg), D\u00fcsseldorf (1990, 1.450), Fribourg (1991, 730) et Munich (1998, 1.100) ont m\u00eame \u00e9t\u00e9 fond\u00e9es dans des villes fortement marqu\u00e9es par le catholicisme, loin de la \"Bible Belt\", aucune d&rsquo;entre elles n&rsquo;avait ou n&rsquo;a une empreinte russe allemande.<\/p>\n\n<p>Bien que la litt\u00e9rature scientifique typifie toujours les \u00e9coles \u00e9vang\u00e9liques ind\u00e9pendantes comme \"russes-allemandes\", on ne trouve pas un seul collaborateur \u00e0 plein temps issu(e) de l&rsquo;immigration russe dans les associations fa\u00eeti\u00e8res AEBS et plus tard VEBS. Au sein du comit\u00e9 directeur de la VEBS, les repr\u00e9sentants des autorit\u00e9s scolaires d&rsquo;origine russe ne repr\u00e9sentent tout au plus qu&rsquo;un tiers - ce qui correspond \u00e0 peu pr\u00e8s au nombre d&rsquo;\u00e9l\u00e8ves et d&rsquo;enfants en cr\u00e8che - m\u00eame si l&rsquo;on fait preuve de g\u00e9n\u00e9rosit\u00e9. <\/p>\n\n<p>Derri\u00e8re l&rsquo;unit\u00e9 de l&rsquo;association nationale VEBS, qui repose essentiellement sur le fondement commun de la foi de l&rsquo;Alliance, il existe ainsi en interne une diversit\u00e9 enrichissante de types d&rsquo;\u00e9coles et de cr\u00e8ches - tout \u00e0 fait semblable \u00e0 la structure de l&rsquo;Alliance \u00e9vang\u00e9lique en Allemagne.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Au d\u00e9but de la nouvelle ann\u00e9e scolaire, les \u00e9coles August Hermann Franke de Hambourg f\u00eatent leurs 30 ans d&rsquo;existence. Cet anniversaire d&rsquo;une institution scolaire en pleine croissance, qui accueille d\u00e9sormais plus de 1100 \u00e9l\u00e8ves et qui est respect\u00e9e par les autorit\u00e9s, dans une grande ville allemande, montre que les \u00e9coles \u00e9vang\u00e9liques libres ne sont en aucun cas, dans leur majorit\u00e9, \"allemandes de Russie\" ou implant\u00e9es dans des bastions \u00e9vang\u00e9liques (\"Bible Belt\"), comme on peut le lire r\u00e9guli\u00e8rement dans des articles scientifiques. <\/p>\n","protected":false},"author":2,"featured_media":40026,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[51,295],"tags":[],"class_list":["post-40923","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-kategorisiert","category-page-daccueil"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DDPS : une clart\u00e9 spirituelle qui n&#039;emp\u00eache pas la diversit\u00e9 - VEBS e.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vebs.de\/fr\/vebs-geistlich-klar-und-trotzdem-vielfaeltig\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DDPS : une clart\u00e9 spirituelle qui n&#039;emp\u00eache pas la diversit\u00e9 - VEBS e.V.\" \/>\n<meta property=\"og:description\" content=\"Au d\u00e9but de la nouvelle ann\u00e9e scolaire, les \u00e9coles August Hermann Franke de Hambourg f\u00eatent leurs 30 ans d&#039;existence. Cet anniversaire d&#039;une institution scolaire en pleine croissance, qui accueille d\u00e9sormais plus de 1100 \u00e9l\u00e8ves et qui est respect\u00e9e par les autorit\u00e9s, dans une grande ville allemande, montre que les \u00e9coles \u00e9vang\u00e9liques libres ne sont en aucun cas, dans leur majorit\u00e9, &quot;allemandes de Russie&quot; ou implant\u00e9es dans des bastions \u00e9vang\u00e9liques (&quot;Bible Belt&quot;), comme on peut le lire r\u00e9guli\u00e8rement dans des articles scientifiques.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vebs.de\/fr\/vebs-geistlich-klar-und-trotzdem-vielfaeltig\/\" \/>\n<meta property=\"og:site_name\" content=\"VEBS e.V.\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-20T07:17:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-17T12:48:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vebs.de\/wp-content\/uploads\/2022\/04\/drawers-2752959_960_720.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"594\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Norman Kronenwett\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Norman Kronenwett\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.vebs.de\/fr\/vebs-geistlich-klar-und-trotzdem-vielfaeltig\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.vebs.de\/fr\/vebs-geistlich-klar-und-trotzdem-vielfaeltig\/\"},\"author\":{\"name\":\"Norman Kronenwett\",\"@id\":\"https:\/\/www.vebs.de\/fr\/#\/schema\/person\/2c2d36384cb9c56b0b47223c61f35512\"},\"headline\":\"DDPS : une clart\u00e9 spirituelle qui n&#8217;emp\u00eache pas la diversit\u00e9\",\"datePublished\":\"2022-04-20T07:17:00+00:00\",\"dateModified\":\"2025-09-17T12:48:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.vebs.de\/fr\/vebs-geistlich-klar-und-trotzdem-vielfaeltig\/\"},\"wordCount\":413,\"publisher\":{\"@id\":\"https:\/\/www.vebs.de\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.vebs.de\/fr\/vebs-geistlich-klar-und-trotzdem-vielfaeltig\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.vebs.de\/wp-content\/uploads\/2022\/04\/drawers-2752959_960_720.jpg\",\"articleSection\":[\"Nicht kategorisiert\",\"Page d'accueil\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.vebs.de\/fr\/vebs-geistlich-klar-und-trotzdem-vielfaeltig\/\",\"url\":\"https:\/\/www.vebs.de\/fr\/vebs-geistlich-klar-und-trotzdem-vielfaeltig\/\",\"name\":\"DDPS : une clart\u00e9 spirituelle qui n'emp\u00eache pas la diversit\u00e9 - VEBS e.V.\",\"isPartOf\":{\"@id\":\"https:\/\/www.vebs.de\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.vebs.de\/fr\/vebs-geistlich-klar-und-trotzdem-vielfaeltig\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.vebs.de\/fr\/vebs-geistlich-klar-und-trotzdem-vielfaeltig\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.vebs.de\/wp-content\/uploads\/2022\/04\/drawers-2752959_960_720.jpg\",\"datePublished\":\"2022-04-20T07:17:00+00:00\",\"dateModified\":\"2025-09-17T12:48:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.vebs.de\/fr\/vebs-geistlich-klar-und-trotzdem-vielfaeltig\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.vebs.de\/fr\/vebs-geistlich-klar-und-trotzdem-vielfaeltig\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.vebs.de\/fr\/vebs-geistlich-klar-und-trotzdem-vielfaeltig\/#primaryimage\",\"url\":\"https:\/\/www.vebs.de\/wp-content\/uploads\/2022\/04\/drawers-2752959_960_720.jpg\",\"contentUrl\":\"https:\/\/www.vebs.de\/wp-content\/uploads\/2022\/04\/drawers-2752959_960_720.jpg\",\"width\":960,\"height\":594},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.vebs.de\/fr\/vebs-geistlich-klar-und-trotzdem-vielfaeltig\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.vebs.de\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DDPS : une clart\u00e9 spirituelle qui n&#8217;emp\u00eache pas la diversit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.vebs.de\/fr\/#website\",\"url\":\"https:\/\/www.vebs.de\/fr\/\",\"name\":\"VEBS e.V.\",\"description\":\"Verband Evangelischer Bekenntnisschulen e.V.\",\"publisher\":{\"@id\":\"https:\/\/www.vebs.de\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.vebs.de\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.vebs.de\/fr\/#organization\",\"name\":\"Verband Evangelischer Bekenntnisschulen e.V. (VEBS)\",\"url\":\"https:\/\/www.vebs.de\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.vebs.de\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.vebs.de\/wp-content\/uploads\/2021\/03\/vebs-Logo-v2_rot_300x177.png\",\"contentUrl\":\"https:\/\/www.vebs.de\/wp-content\/uploads\/2021\/03\/vebs-Logo-v2_rot_300x177.png\",\"width\":300,\"height\":177,\"caption\":\"Verband Evangelischer Bekenntnisschulen e.V. (VEBS)\"},\"image\":{\"@id\":\"https:\/\/www.vebs.de\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.vebs.de\/fr\/#\/schema\/person\/2c2d36384cb9c56b0b47223c61f35512\",\"name\":\"Norman Kronenwett\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.vebs.de\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1511a118cf7ccb954d109f2321b19631ccfe59681fe02aad730617e0a0ff49c2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1511a118cf7ccb954d109f2321b19631ccfe59681fe02aad730617e0a0ff49c2?s=96&d=mm&r=g\",\"caption\":\"Norman Kronenwett\"},\"url\":\"https:\/\/www.vebs.de\/fr\/author\/norman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DDPS : une clart\u00e9 spirituelle qui n'emp\u00eache pas la diversit\u00e9 - VEBS e.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vebs.de\/fr\/vebs-geistlich-klar-und-trotzdem-vielfaeltig\/","og_locale":"fr_FR","og_type":"article","og_title":"DDPS : une clart\u00e9 spirituelle qui n'emp\u00eache pas la diversit\u00e9 - VEBS e.V.","og_description":"Au d\u00e9but de la nouvelle ann\u00e9e scolaire, les \u00e9coles August Hermann Franke de Hambourg f\u00eatent leurs 30 ans d'existence. Cet anniversaire d'une institution scolaire en pleine croissance, qui accueille d\u00e9sormais plus de 1100 \u00e9l\u00e8ves et qui est respect\u00e9e par les autorit\u00e9s, dans une grande ville allemande, montre que les \u00e9coles \u00e9vang\u00e9liques libres ne sont en aucun cas, dans leur majorit\u00e9, \"allemandes de Russie\" ou implant\u00e9es dans des bastions \u00e9vang\u00e9liques (\"Bible Belt\"), comme on peut le lire r\u00e9guli\u00e8rement dans des articles scientifiques.","og_url":"https:\/\/www.vebs.de\/fr\/vebs-geistlich-klar-und-trotzdem-vielfaeltig\/","og_site_name":"VEBS e.V.","article_published_time":"2022-04-20T07:17:00+00:00","article_modified_time":"2025-09-17T12:48:29+00:00","og_image":[{"width":960,"height":594,"url":"https:\/\/www.vebs.de\/wp-content\/uploads\/2022\/04\/drawers-2752959_960_720.jpg","type":"image\/jpeg"}],"author":"Norman Kronenwett","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Norman Kronenwett","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vebs.de\/fr\/vebs-geistlich-klar-und-trotzdem-vielfaeltig\/#article","isPartOf":{"@id":"https:\/\/www.vebs.de\/fr\/vebs-geistlich-klar-und-trotzdem-vielfaeltig\/"},"author":{"name":"Norman Kronenwett","@id":"https:\/\/www.vebs.de\/fr\/#\/schema\/person\/2c2d36384cb9c56b0b47223c61f35512"},"headline":"DDPS : une clart\u00e9 spirituelle qui n&#8217;emp\u00eache pas la diversit\u00e9","datePublished":"2022-04-20T07:17:00+00:00","dateModified":"2025-09-17T12:48:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vebs.de\/fr\/vebs-geistlich-klar-und-trotzdem-vielfaeltig\/"},"wordCount":413,"publisher":{"@id":"https:\/\/www.vebs.de\/fr\/#organization"},"image":{"@id":"https:\/\/www.vebs.de\/fr\/vebs-geistlich-klar-und-trotzdem-vielfaeltig\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vebs.de\/wp-content\/uploads\/2022\/04\/drawers-2752959_960_720.jpg","articleSection":["Nicht kategorisiert","Page d'accueil"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.vebs.de\/fr\/vebs-geistlich-klar-und-trotzdem-vielfaeltig\/","url":"https:\/\/www.vebs.de\/fr\/vebs-geistlich-klar-und-trotzdem-vielfaeltig\/","name":"DDPS : une clart\u00e9 spirituelle qui n'emp\u00eache pas la diversit\u00e9 - VEBS e.V.","isPartOf":{"@id":"https:\/\/www.vebs.de\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vebs.de\/fr\/vebs-geistlich-klar-und-trotzdem-vielfaeltig\/#primaryimage"},"image":{"@id":"https:\/\/www.vebs.de\/fr\/vebs-geistlich-klar-und-trotzdem-vielfaeltig\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vebs.de\/wp-content\/uploads\/2022\/04\/drawers-2752959_960_720.jpg","datePublished":"2022-04-20T07:17:00+00:00","dateModified":"2025-09-17T12:48:29+00:00","breadcrumb":{"@id":"https:\/\/www.vebs.de\/fr\/vebs-geistlich-klar-und-trotzdem-vielfaeltig\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vebs.de\/fr\/vebs-geistlich-klar-und-trotzdem-vielfaeltig\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vebs.de\/fr\/vebs-geistlich-klar-und-trotzdem-vielfaeltig\/#primaryimage","url":"https:\/\/www.vebs.de\/wp-content\/uploads\/2022\/04\/drawers-2752959_960_720.jpg","contentUrl":"https:\/\/www.vebs.de\/wp-content\/uploads\/2022\/04\/drawers-2752959_960_720.jpg","width":960,"height":594},{"@type":"BreadcrumbList","@id":"https:\/\/www.vebs.de\/fr\/vebs-geistlich-klar-und-trotzdem-vielfaeltig\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vebs.de\/fr\/"},{"@type":"ListItem","position":2,"name":"DDPS : une clart\u00e9 spirituelle qui n&#8217;emp\u00eache pas la diversit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.vebs.de\/fr\/#website","url":"https:\/\/www.vebs.de\/fr\/","name":"VEBS e.V.","description":"Verband Evangelischer Bekenntnisschulen e.V.","publisher":{"@id":"https:\/\/www.vebs.de\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vebs.de\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vebs.de\/fr\/#organization","name":"Verband Evangelischer Bekenntnisschulen e.V. (VEBS)","url":"https:\/\/www.vebs.de\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vebs.de\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.vebs.de\/wp-content\/uploads\/2021\/03\/vebs-Logo-v2_rot_300x177.png","contentUrl":"https:\/\/www.vebs.de\/wp-content\/uploads\/2021\/03\/vebs-Logo-v2_rot_300x177.png","width":300,"height":177,"caption":"Verband Evangelischer Bekenntnisschulen e.V. (VEBS)"},"image":{"@id":"https:\/\/www.vebs.de\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.vebs.de\/fr\/#\/schema\/person\/2c2d36384cb9c56b0b47223c61f35512","name":"Norman Kronenwett","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vebs.de\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1511a118cf7ccb954d109f2321b19631ccfe59681fe02aad730617e0a0ff49c2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1511a118cf7ccb954d109f2321b19631ccfe59681fe02aad730617e0a0ff49c2?s=96&d=mm&r=g","caption":"Norman Kronenwett"},"url":"https:\/\/www.vebs.de\/fr\/author\/norman\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vebs.de\/fr\/wp-json\/wp\/v2\/posts\/40923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vebs.de\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vebs.de\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vebs.de\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vebs.de\/fr\/wp-json\/wp\/v2\/comments?post=40923"}],"version-history":[{"count":2,"href":"https:\/\/www.vebs.de\/fr\/wp-json\/wp\/v2\/posts\/40923\/revisions"}],"predecessor-version":[{"id":48780,"href":"https:\/\/www.vebs.de\/fr\/wp-json\/wp\/v2\/posts\/40923\/revisions\/48780"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vebs.de\/fr\/wp-json\/wp\/v2\/media\/40026"}],"wp:attachment":[{"href":"https:\/\/www.vebs.de\/fr\/wp-json\/wp\/v2\/media?parent=40923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vebs.de\/fr\/wp-json\/wp\/v2\/categories?post=40923"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vebs.de\/fr\/wp-json\/wp\/v2\/tags?post=40923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}