{"id":41125,"date":"2020-10-28T13:43:33","date_gmt":"2020-10-28T12:43:33","guid":{"rendered":"https:\/\/www.vebs.de\/association\/"},"modified":"2025-10-30T14:31:50","modified_gmt":"2025-10-30T13:31:50","slug":"verband","status":"publish","type":"page","link":"https:\/\/www.vebs.de\/fr\/verband\/","title":{"rendered":"Association"},"content":{"rendered":"\n<h1 class=\"wp-block-ecw-ueberschrift h1 text-left\" style=\"\">\u00c0 propos de nous<\/h1>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>95 membres<br\/>avec 216 \u00e9tablissements d&rsquo;enseignement<br\/>(56 cr\u00e8ches &amp; 160 \u00e9coles)<br\/>sur 134 sites<br\/>avec 39.500 \u00e9l\u00e8ves &amp; enfants de cr\u00e8ches<br\/>et plus de 6.000 collaborateurs,<br\/>soutenu par des initiatives de parents chr\u00e9tiens&#8230;<\/p>\n<cite>- <strong>voici la Verband Evangelical schools und Kitas (VEBS) !<\/strong><\/cite><\/blockquote>\n\n<p>L&rsquo;Association des \u00e9coles et cr\u00e8ches confessionnelles protestantes (VEBS e.V.) repr\u00e9sente les int\u00e9r\u00eats de 207 \u00e9coles et cr\u00e8ches confessionnelles chr\u00e9tiennes. Elles ont toutes \u00e9t\u00e9 fond\u00e9es par des parents qui ont ainsi exerc\u00e9 un droit fondamental de notre Constitution (article 7, paragraphe 4 de la Loi fondamentale). <\/p>\n\n<p>Ils partagent en tant que <a href=\"https:\/\/www.ead.de\/ueber-uns\/\" data-type=\"URL\" data-id=\"https:\/\/www.ead.de\/ueber-uns\/\" target=\"_blank\" rel=\"noreferrer noopener\">confession de foi la \"base commune de la foi de l&rsquo;Alliance \u00e9vang\u00e9lique en Allemagne\", ils<\/a> sont donc ind\u00e9pendants (\"libres\") des \u00e9glises (\u00e9vang\u00e9liques r\u00e9gionales par exemple).<\/p>\n\n<p>En tant qu&rsquo;association nationale, la VEBS est un foyer spirituel, une plate-forme et un prestataire de services (conseil, formation continue, recherche de collaborateurs&#8230;), un organisateur de manifestations et un d\u00e9fenseur des int\u00e9r\u00eats des Evangelical schools et des cr\u00e8ches ind\u00e9pendantes - et aussi un d\u00e9fenseur en cas d&rsquo;attaques infond\u00e9es.<\/p>\n\n<p>Les Evangelical schools se caract\u00e9risent par le fait qu&rsquo;elles ne sont tenues de suivre que les objectifs d&rsquo;enseignement de l&rsquo;<sup>\u00c9tat1<\/sup>, et non les <strong>programmes\/plans<\/strong> d&rsquo;\u00e9ducation.<\/p>\n\n<p>La constitution de la Rh\u00e9nanie-du-Nord-Westphalie stipule par exemple que \"dans les Evangelical schools, les enfants de confession catholique ou protestante ou d&rsquo;une autre communaut\u00e9 religieuse sont <strong>instruits et \u00e9duqu\u00e9s selon les principes de la confession concern\u00e9e<\/strong>\"<sup>1<\/sup>.  <\/p>\n\n<p>Les Evangelical schools sont donc autoris\u00e9es \u00e0 \u00e9laborer et \u00e0 enseigner <strong>leurs propres<\/strong> <sup>programmes2<\/sup> - ceux-ci doivent \u00eatre approuv\u00e9s par l&rsquo;inspection scolaire du Land.<\/p>\n\n<p><strong>L&rsquo;ensemble du quotidien d&rsquo;une \u00e9cole confessionnelle (donc aussi toutes les mati\u00e8res scolaires) doit \u00eatre impr\u00e9gn\u00e9\/marqu\u00e9 par la confession chr\u00e9tienne<\/strong> (de m\u00eame que les \u00e9coles Waldorf ou Montessori doivent \u00eatre marqu\u00e9es par les principes p\u00e9dagogiques respectifs)<sup>.3<\/sup><\/p>\n\n<p>Nous utilisons cette libert\u00e9, tout en respectant les objectifs d&rsquo;enseignement de l&rsquo;\u00c9tat, pour concevoir l&rsquo;\u00e9cole avec nos propres m\u00e9thodes et contenus d&rsquo;enseignement, marqu\u00e9s par notre confession de foi.  <\/p>\n\n<p>Pour \u00e9viter tout malentendu : Nos \u00e9coles respectent en grande partie les programmes scolaires, mais vont souvent au-del\u00e0 en fonction de la confession de foi. En particulier en ce qui concerne les questions de sens et de valeurs, nous discutons, en plus des contenus du programme scolaire de l&rsquo;\u00c9tat, de tout ce qui est important pour la confession de l&rsquo;\u00e9cole. <\/p>\n\n<p>Et oui : nous pouvons <strong>faire de la publicit\u00e9 pour notre confession<\/strong> dans les Evangelical schools - mais il va de soi que les enfants et les jeunes d\u00e9cident pour eux-m\u00eames personnellement (\"interdiction d&rsquo;\u00eatre submerg\u00e9s\").  <\/p>\n\n<p>Dans les Evangelical schools et les cr\u00e8ches chr\u00e9tiennes du VEBS, seuls travaillent des collaborateurs qui partagent cette confession de foi - il s&rsquo;agit l\u00e0 aussi d&rsquo;une obligation de la Loi <sup>fondamentale3<\/sup>.<\/p>\n\n<p><strong>Bien entendu, la VEBS soutient \u00e9galement les (initiatives) de parents lors de la cr\u00e9ation d&rsquo;<a href=\"https:\/\/www.vebs.de\/fr\/verband\/kitagruendung\/\">\u00e9coles et de cr\u00e8ches<\/a>!<\/strong><\/p>\n\n<p><\/p>\n\n<p>Vous souhaitez nous aider dans ce travail ? <a href=\"https:\/\/www.vebs.de\/bewerbung\/\" data-type=\"URL\" data-id=\"https:\/\/www.vebs.de\/bewerbung\/\" target=\"_blank\" rel=\"noreferrer noopener\">Vous trouverez nos offres d&#8217;emploi ici<\/a>. <br\/>Notre <strong>compte pour les dons : DE88 5009 2100 0001 7675 00<\/strong>.   <\/p>\n\n<p><\/p>\n\n<p><\/p>\n\n<h2 class=\"wp-block-ecw-ueberschrift h2 text-left\" style=\"\">Principaux fondements juridiques et jugements des deux plus hautes juridictions allemandes concernant les Evangelical schools<\/h2>\n\n<p>\"<em>Le droit de cr\u00e9er des \u00e9coles priv\u00e9es est garanti. Les \u00e9coles priv\u00e9es rempla\u00e7ant les \u00e9coles publiques sont soumises \u00e0 l&rsquo;autorisation de l&rsquo;Etat et sont r\u00e9gies par les lois des L\u00e4nder. L&rsquo;autorisation est accord\u00e9e si les \u00e9coles priv\u00e9es ne sont pas inf\u00e9rieures aux \u00e9coles publiques en ce qui concerne les objectifs et les installations d&rsquo;enseignement ainsi que la formation scientifique de leurs enseignants, et si elles ne favorisent pas une diff\u00e9renciation des \u00e9l\u00e8ves en fonction de la situation de propri\u00e9t\u00e9 des parents. L&rsquo;autorisation doit \u00eatre refus\u00e9e si la situation \u00e9conomique et juridique des enseignants n&rsquo;est pas suffisamment garantie.   <\/em><\/p>\n\n<p><em>Une \u00e9cole primaire priv\u00e9e (aujourd&rsquo;hui : \u00e9cole \u00e9l\u00e9mentaire) ne doit \u00eatre autoris\u00e9e que si l&rsquo;administration de l&rsquo;enseignement reconna\u00eet un int\u00e9r\u00eat p\u00e9dagogique particulier ou, \u00e0 la demande des d\u00e9tenteurs de l&rsquo;autorit\u00e9 parentale, si elle doit \u00eatre cr\u00e9\u00e9e en tant qu&rsquo;\u00e9cole communautaire, \u00e9cole confessionnelle ou \u00e9cole de conviction et s&rsquo;il n&rsquo;existe pas d&rsquo;\u00e9cole primaire publique de ce type dans la commune<\/em><sup>\"1<\/sup><em>.<\/em><\/p>\n\n<p>\"<em>Dans les Evangelical schools, les enfants de confession catholique, protestante ou d&rsquo;une autre communaut\u00e9 religieuse sont instruits et \u00e9duqu\u00e9s selon les principes de la confession concern\u00e9e \"<\/em><sup>2<\/sup><em>.<\/em><\/p>\n\n<p>\"<em>Sauf disposition contraire de la pr\u00e9sente loi,<br\/><strong>incombe aux organes responsables de ces \u00e9coles.<\/strong><\/em><\/p>\n\n<ul class=\"wp-block-list\">\n<li><em>l&rsquo;organisation de l&rsquo;\u00e9cole, notamment la d\u00e9cision concernant<br\/>une empreinte p\u00e9dagogique, religieuse &#8230;particuli\u00e8re,<\/em><\/li>\n\n\n\n<li><em>la d\u00e9finition des <strong>m\u00e9thodes d&rsquo;enseignement et de formation <\/strong>, et<\/em><\/li>\n\n\n\n<li><em>du <strong>contenu de l&rsquo;enseignement<\/strong> et<\/em><\/li>\n\n\n\n<li><em>l&rsquo;organisation de l&rsquo;enseignement<\/em><\/li>\n<\/ul>\n\n<p><em><strong>m\u00eame en d\u00e9rogation aux r\u00e8gles applicables aux \u00e9coles g\u00e9r\u00e9es par les pouvoirs publics<\/strong><\/em>\"<sup>3<\/sup><em>.<\/em><\/p>\n\n<p><em>\"Une \u00e9cole confessionnelle pr\u00e9suppose l&rsquo;homog\u00e9n\u00e9it\u00e9 de la <strong>confession de foi des parents, des \u00e9l\u00e8ves et des enseignants<\/strong>, <strong>qui caract\u00e9rise l&rsquo;\u00e9cole ainsi que l&rsquo;ensemble de son enseignement<\/strong><\/em>\".<sup><a href=\"https:\/\/www.vebs.de\/fr\/verband\/tribunal-administratif-federal-arret-du-19-02-1992-6-c-3-91\/\" data-type=\"page\" data-id=\"6764\">4<\/a><\/sup><\/p>\n\n<p>\"<em>Ce qui importe (pour les Evangelical schools), c&rsquo;est de savoir si <strong>les m\u00eames connaissances et comp\u00e9tences sont transmises<\/strong>, sans pr\u00e9judice d&rsquo;un <strong>enseignement qui se caract\u00e9rise par une responsabilit\u00e9<\/strong> propre \u00e0 partir d&rsquo;une base id\u00e9ologique propre <strong>, avec des m\u00e9thodes et des contenus d&rsquo;enseignement adapt\u00e9s \u00e0 cette<\/strong> base.<\/em><\/p>\n\n<p><em>En ce sens, il n&rsquo;<strong>y a pas d&rsquo;exigence de similitude avec les \u00e9coles publiques<\/strong>, mais seulement d&rsquo;\u00e9quivalence<\/em>.<sup>\"5<\/sup><\/p>\n\n<p>\"<em>&#8230; les \u00e9coles priv\u00e9es de remplacement sont libres de poursuivre, outre les objectifs d&rsquo;enseignement prescrits par l&rsquo;\u00c9tat, y compris les objectifs \u00e9ducatifs, d&rsquo;autres objectifs \u00e9ducatifs qui ne sont en tout cas pas en contradiction avec les objectifs de l&rsquo;\u00c9tat, d&rsquo;autant plus que les objectifs \u00e9ducatifs de l&rsquo;\u00c9tat laissent typiquement de la place pour un remplissage du contenu dans l&rsquo;enseignement concret \"<\/em><sup>4<\/sup><em>.<\/em><\/p>\n\n<p><em>\"Le caract\u00e8re d&rsquo;une \u00e9cole confessionnelle n&rsquo;est pas modifi\u00e9 par le fait qu&rsquo;une minorit\u00e9 d&rsquo;\u00e9l\u00e8ves proviennent d&rsquo;un foyer qui n&rsquo;appartient pas \u00e0 la communaut\u00e9 religieuse des personnes qui soutiennent l&rsquo;\u00e9cole et des enseignants&#8230;\"<\/em><sup><a data-type=\"page\" data-id=\"6764\" href=\"https:\/\/www.vebs.de\/fr\/verband\/tribunal-administratif-federal-arret-du-19-02-1992-6-c-3-91\/\">4<\/a><\/sup><\/p>\n\n<p><em><strong>\"La tol\u00e9rance ne signifie pas l&rsquo;ouverture et la neutralit\u00e9 dans le sens o\u00f9 l&rsquo;on ne devrait pas apprendre aux \u00e9l\u00e8ves \u00e0 d\u00e9velopper une certaine conviction personnelle, \u00e0 l&rsquo;affirmer et, si n\u00e9cessaire, \u00e0 la d\u00e9fendre<\/strong>&#8230;<br\/><strong>Ce minimum de tol\u00e9rance interdit<\/strong> certes de d\u00e9valoriser ainsi que, en particulier, de diffamer des convictions divergentes, mais <strong>en aucun cas <\/strong><strong> de faire la promotion de sa propre conviction<\/strong>\".<\/em><sup><a href=\"https:\/\/www.vebs.de\/fr\/verband\/tribunal-administratif-federal-arret-du-19-02-1992-6-c-3-91\/\" data-type=\"page\" data-id=\"6764\">4<\/a><\/sup><\/p>\n\n<p>\"<em>Pour le minimum requis par la Constitution en mati\u00e8re de transmission des valeurs \u00e0 l&rsquo;\u00e9cole, il n&rsquo;est pas n\u00e9cessaire d&rsquo;enseigner la religion ni m\u00eame une mati\u00e8re particuli\u00e8re. D&rsquo;autres mati\u00e8res, telles que l&rsquo;allemand ou l&rsquo;\u00e9ducation civique, sont \u00e9galement appropri\u00e9es pour traiter des questions \u00e9thiques\". <\/em><sup>6<\/sup><\/p>\n\n<p>\"<em><strong>Le droit du Land et la pratique des autorit\u00e9s scolaires en mati\u00e8re d&rsquo;autorisation ne doivent<\/strong><\/em><sup>pas<\/sup><em><strong>exiger du pouvoir organisateur priv\u00e9 qu&rsquo;il remplisse d&rsquo;autres conditions d&rsquo;autorisation que celles \u00e9num\u00e9r\u00e9es \u00e0 l&rsquo;article 7, paragraphe 4, troisi\u00e8me phrase, de la Loi fondamentale<\/strong>.<\/em><\/p>\n\n<p><\/p>\n\n<h3 class=\"wp-block-ecw-ueberschrift h3 text-left\" style=\"\">R\u00e9f\u00e9rences<\/h3>\n\n<p><sup>1<\/sup> Loi fondamentale Article 7, paragraphes 4 et 5<\/p>\n\n<p><sup>2<\/sup> Constitution du Land de Rh\u00e9nanie-du-Nord-Westphalie, \u00a7 12 alin\u00e9a 3 phrase 2<\/p>\n\n<p><sup>3<\/sup> Loi saxonne sur les \u00e9coles ind\u00e9pendantes, \u00a7 2, alin\u00e9a 2, phrase 2<\/p>\n\n<p><sup>4<\/sup> <a href=\"https:\/\/www.vebs.de\/fr\/verband\/tribunal-administratif-federal-arret-du-19-02-1992-6-c-3-91\/\" data-type=\"page\" data-id=\"6764\" target=\"_blank\" rel=\"noreferrer noopener\">Tribunal administratif f\u00e9d\u00e9ral, arr\u00eat du 19.02.1992, r\u00e9f. : 6 C 3\/91, principe 1<\/a><\/p>\n\n<p><sup>5<\/sup> Cour constitutionnelle f\u00e9d\u00e9rale, d\u00e9cisions du 9.3.1994 (1 BvR 682, 712\/88) et du 8.6.2011 (1 BvR 759\/08, 733\/09)<\/p>\n\n<p><sup>6<\/sup> Tribunal administratif f\u00e9d\u00e9ral, d\u00e9cision du 29.4.2019 (6 B 141.18)<\/p>\n\n<p><sup>7<\/sup> Tribunal administratif f\u00e9d\u00e9ral, arr\u00eats du 11.3.1966 (7 C 194.64) et du 30.1.2013 (6 C 6.12)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>95 membresavec 216 \u00e9tablissements d&rsquo;enseignement(56 cr\u00e8ches &amp; 160 \u00e9coles)sur 134 sitesavec 39.500 \u00e9l\u00e8ves &amp; enfants de cr\u00e8cheset plus de 6.000 collaborateurs,soutenu par des initiatives de parents chr\u00e9tiens&#8230; - voici la Verband Evangelical schools und Kitas (VEBS) ! L&rsquo;Association des \u00e9coles et cr\u00e8ches confessionnelles protestantes (VEBS e.V.) repr\u00e9sente les int\u00e9r\u00eats de 207 \u00e9coles et cr\u00e8ches confessionnelles [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-41125","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Association - VEBS e.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vebs.de\/fr\/verband\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Association - VEBS e.V.\" \/>\n<meta property=\"og:description\" content=\"95 membresavec 216 \u00e9tablissements d&rsquo;enseignement(56 cr\u00e8ches &amp; 160 \u00e9coles)sur 134 sitesavec 39.500 \u00e9l\u00e8ves &amp; enfants de cr\u00e8cheset plus de 6.000 collaborateurs,soutenu par des initiatives de parents chr\u00e9tiens&#8230; - voici la Verband Evangelical schools und Kitas (VEBS) ! L&rsquo;Association des \u00e9coles et cr\u00e8ches confessionnelles protestantes (VEBS e.V.) repr\u00e9sente les int\u00e9r\u00eats de 207 \u00e9coles et cr\u00e8ches confessionnelles [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vebs.de\/fr\/verband\/\" \/>\n<meta property=\"og:site_name\" content=\"VEBS e.V.\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T13:31:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.vebs.de\/fr\/verband\/\",\"url\":\"https:\/\/www.vebs.de\/fr\/verband\/\",\"name\":\"Association - VEBS e.V.\",\"isPartOf\":{\"@id\":\"https:\/\/www.vebs.de\/fr\/#website\"},\"datePublished\":\"2020-10-28T12:43:33+00:00\",\"dateModified\":\"2025-10-30T13:31:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.vebs.de\/fr\/verband\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.vebs.de\/fr\/verband\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.vebs.de\/fr\/verband\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.vebs.de\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Association\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.vebs.de\/fr\/#website\",\"url\":\"https:\/\/www.vebs.de\/fr\/\",\"name\":\"VEBS e.V.\",\"description\":\"Verband Evangelischer Bekenntnisschulen e.V.\",\"publisher\":{\"@id\":\"https:\/\/www.vebs.de\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.vebs.de\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.vebs.de\/fr\/#organization\",\"name\":\"Verband Evangelischer Bekenntnisschulen e.V. (VEBS)\",\"url\":\"https:\/\/www.vebs.de\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.vebs.de\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.vebs.de\/wp-content\/uploads\/2021\/03\/vebs-Logo-v2_rot_300x177.png\",\"contentUrl\":\"https:\/\/www.vebs.de\/wp-content\/uploads\/2021\/03\/vebs-Logo-v2_rot_300x177.png\",\"width\":300,\"height\":177,\"caption\":\"Verband Evangelischer Bekenntnisschulen e.V. (VEBS)\"},\"image\":{\"@id\":\"https:\/\/www.vebs.de\/fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Association - VEBS e.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vebs.de\/fr\/verband\/","og_locale":"fr_FR","og_type":"article","og_title":"Association - VEBS e.V.","og_description":"95 membresavec 216 \u00e9tablissements d&rsquo;enseignement(56 cr\u00e8ches &amp; 160 \u00e9coles)sur 134 sitesavec 39.500 \u00e9l\u00e8ves &amp; enfants de cr\u00e8cheset plus de 6.000 collaborateurs,soutenu par des initiatives de parents chr\u00e9tiens&#8230; - voici la Verband Evangelical schools und Kitas (VEBS) ! L&rsquo;Association des \u00e9coles et cr\u00e8ches confessionnelles protestantes (VEBS e.V.) repr\u00e9sente les int\u00e9r\u00eats de 207 \u00e9coles et cr\u00e8ches confessionnelles [&hellip;]","og_url":"https:\/\/www.vebs.de\/fr\/verband\/","og_site_name":"VEBS e.V.","article_modified_time":"2025-10-30T13:31:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vebs.de\/fr\/verband\/","url":"https:\/\/www.vebs.de\/fr\/verband\/","name":"Association - VEBS e.V.","isPartOf":{"@id":"https:\/\/www.vebs.de\/fr\/#website"},"datePublished":"2020-10-28T12:43:33+00:00","dateModified":"2025-10-30T13:31:50+00:00","breadcrumb":{"@id":"https:\/\/www.vebs.de\/fr\/verband\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vebs.de\/fr\/verband\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vebs.de\/fr\/verband\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vebs.de\/fr\/"},{"@type":"ListItem","position":2,"name":"Association"}]},{"@type":"WebSite","@id":"https:\/\/www.vebs.de\/fr\/#website","url":"https:\/\/www.vebs.de\/fr\/","name":"VEBS e.V.","description":"Verband Evangelischer Bekenntnisschulen e.V.","publisher":{"@id":"https:\/\/www.vebs.de\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vebs.de\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vebs.de\/fr\/#organization","name":"Verband Evangelischer Bekenntnisschulen e.V. (VEBS)","url":"https:\/\/www.vebs.de\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vebs.de\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.vebs.de\/wp-content\/uploads\/2021\/03\/vebs-Logo-v2_rot_300x177.png","contentUrl":"https:\/\/www.vebs.de\/wp-content\/uploads\/2021\/03\/vebs-Logo-v2_rot_300x177.png","width":300,"height":177,"caption":"Verband Evangelischer Bekenntnisschulen e.V. (VEBS)"},"image":{"@id":"https:\/\/www.vebs.de\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.vebs.de\/fr\/wp-json\/wp\/v2\/pages\/41125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vebs.de\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.vebs.de\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.vebs.de\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vebs.de\/fr\/wp-json\/wp\/v2\/comments?post=41125"}],"version-history":[{"count":3,"href":"https:\/\/www.vebs.de\/fr\/wp-json\/wp\/v2\/pages\/41125\/revisions"}],"predecessor-version":[{"id":49290,"href":"https:\/\/www.vebs.de\/fr\/wp-json\/wp\/v2\/pages\/41125\/revisions\/49290"}],"wp:attachment":[{"href":"https:\/\/www.vebs.de\/fr\/wp-json\/wp\/v2\/media?parent=41125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}