{"id":46109,"date":"2020-08-12T14:47:14","date_gmt":"2020-08-12T12:47:14","guid":{"rendered":"https:\/\/www.vebs.de\/datenschutzerklaerung\/"},"modified":"2025-09-05T11:12:11","modified_gmt":"2025-09-05T09:12:11","slug":"datenschutzerklaerung","status":"publish","type":"page","link":"https:\/\/www.vebs.de\/fi\/datenschutzerklaerung\/","title":{"rendered":"Datenschutz"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\">Datenschutzerkl\u00e4rung<\/h1>\n\n<p>Stand: 3. September 2024<\/p>\n\n<h2 class=\"wp-block-heading\">Inhalts\u00fcbersicht<\/h2>\n\n<ul class=\"wp-block-list\">\n<li><a href=\"#m3\">Verantwortlicher<\/a><\/li>\n\n\n\n<li><a href=\"#mOverview\">\u00dcbersicht der Verarbeitungen<\/a><\/li>\n\n\n\n<li><a href=\"#m2427\">Ma\u00dfgebliche Rechtsgrundlagen<\/a><\/li>\n\n\n\n<li><a href=\"#m27\">Sicherheitsma\u00dfnahmen<\/a><\/li>\n\n\n\n<li><a href=\"#m25\">\u00dcbermittlung von personenbezogenen Daten<\/a><\/li>\n\n\n\n<li><a href=\"#m12\">Allgemeine Informationen zur Datenspeicherung und L\u00f6schung<\/a><\/li>\n\n\n\n<li><a href=\"#m10\">Rechte der betroffenen Personen<\/a><\/li>\n\n\n\n<li><a href=\"#m354\">Wahrnehmung von Aufgaben nach Satzung oder Gesch\u00e4ftsordnung<\/a><\/li>\n\n\n\n<li><a href=\"#m225\">Bereitstellung des Onlineangebots und Webhosting<\/a><\/li>\n\n\n\n<li><a href=\"#m134\">Einsatz von Cookies<\/a><\/li>\n\n\n\n<li><a href=\"#m17\">Newsletter und elektronische Benachrichtigungen<\/a><\/li>\n\n\n\n<li><a href=\"#m263\">Webanalyse, Monitoring und Optimierung<\/a><\/li>\n\n\n\n<li><a href=\"#m136\">Pr\u00e4senzen in sozialen Netzwerken (Social Media)<\/a><\/li>\n\n\n\n<li><a href=\"#m328\">Plug-ins und eingebettete Funktionen sowie Inhalte<\/a><\/li>\n\n\n\n<li><a href=\"#m15\">\u00c4nderung und Aktualisierung<\/a><\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\" id=\"m3\">Verantwortlicher<\/h2>\n\n<p>David Gangi<br\/>Verband Evangelischer Bekenntnisschulen e.V.<br\/>Blumentorstr. 16<br\/>76227 Karlsruhe <\/p>\n\n<p>Vertretungsberechtigte Personen: Prof. Dr. Wolfgang Stock<\/p>\n\n<p>E-Mail-Adresse: <a href=\"mailto:datenschutzbeauftragter@vebs.de\">datenschutzbeauftragter@vebs.de<\/a><\/p>\n\n<p>Impressum: vebs.de\/impressum<\/p>\n\n<p style=\"font-size:27px\">Datenschutzbeauftragter:  <\/p>\n\n<p>Hendrik Weiand<br\/>Druseltalstra\u00dfe 125<br\/>34131 Kassel<br\/>E-Mail: weiand@netzwerk-m.de<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"mOverview\">\u00dcbersicht der Verarbeitungen<\/h2>\n\n<p>Die nachfolgende \u00dcbersicht fasst die Arten der verarbeiteten Daten und die Zwecke ihrer Verarbeitung zusammen und verweist auf die betroffenen Personen.<\/p>\n\n<h3 class=\"wp-block-heading\">Arten der verarbeiteten Daten<\/h3>\n\n<ul class=\"wp-block-list\">\n<li>Bestandsdaten.<\/li>\n\n\n\n<li>Standortdaten.<\/li>\n\n\n\n<li>Kontaktdaten.<\/li>\n\n\n\n<li>Inhaltsdaten.<\/li>\n\n\n\n<li>Vertragsdaten.<\/li>\n\n\n\n<li>Nutzungsdaten.<\/li>\n\n\n\n<li>Meta-, Kommunikations- und Verfahrensdaten.<\/li>\n\n\n\n<li>Protokolldaten.<\/li>\n\n\n\n<li>Mitgliederdaten.<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\">Kategorien betroffener Personen<\/h3>\n\n<ul class=\"wp-block-list\">\n<li>Kommunikationspartner.<\/li>\n\n\n\n<li>Nutzer.<\/li>\n\n\n\n<li>Mitglieder.<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\">Zwecke der Verarbeitung<\/h3>\n\n<ul class=\"wp-block-list\">\n<li>Kommunikation.<\/li>\n\n\n\n<li>Sicherheitsma\u00dfnahmen.<\/li>\n\n\n\n<li>Direktmarketing.<\/li>\n\n\n\n<li>Reichweitenmessung.<\/li>\n\n\n\n<li>Organisations- und Verwaltungsverfahren.<\/li>\n\n\n\n<li>Feedback.<\/li>\n\n\n\n<li>Profile mit nutzerbezogenen Informationen.<\/li>\n\n\n\n<li>Bereitstellung unseres Onlineangebotes und Nutzerfreundlichkeit.<\/li>\n\n\n\n<li>Informationstechnische Infrastruktur.<\/li>\n\n\n\n<li>\u00d6ffentlichkeitsarbeit.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\" id=\"m2427\">Ma\u00dfgebliche Rechtsgrundlagen<\/h2>\n\n<p><strong>Ma\u00dfgebliche Rechtsgrundlagen nach der DSGVO: <\/strong>Im Folgenden erhalten Sie eine \u00dcbersicht der Rechtsgrundlagen der DSGVO, auf deren Basis wir personenbezogene Daten verarbeiten. Bitte nehmen Sie zur Kenntnis, dass neben den Regelungen der DSGVO nationale Datenschutzvorgaben in Ihrem bzw. unserem Wohn- oder Sitzland gelten k\u00f6nnen. Sollten ferner im Einzelfall speziellere Rechtsgrundlagen ma\u00dfgeblich sein, teilen wir Ihnen diese in der Datenschutzerkl\u00e4rung mit.  <\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Einwilligung (Art. 6 Abs. 1 S. 1 lit. a) DSGVO)<\/strong> - Die betroffene Person hat ihre Einwilligung in die Verarbeitung der sie betreffenden personenbezogenen Daten f\u00fcr einen spezifischen Zweck oder mehrere bestimmte Zwecke gegeben.<\/li>\n\n\n\n<li><strong>Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f) DSGVO)<\/strong> - die Verarbeitung ist zur Wahrung der berechtigten Interessen des Verantwortlichen oder eines Dritten notwendig, vorausgesetzt, dass die Interessen, Grundrechte und Grundfreiheiten der betroffenen Person, die den Schutz personenbezogener Daten verlangen, nicht \u00fcberwiegen.  <\/li>\n\n\n\n<li>Unser berechtigtes Interesse ist es, Websitebesuchern ein funktional einwandfreies und sicheres Online-Angebot bereitzustellen.<\/li>\n\n\n\n<li>Vertrag \u00fcber die Mitgliedschaft (Satzung) (Art. 6 Abs. 1 S. 1 lit. b) DSGVO).<\/li>\n<\/ul>\n\n<p><strong>Nationale Datenschutzregelungen in Deutschland: <\/strong>Zus\u00e4tzlich zu den Datenschutzregelungen der DSGVO gelten nationale Regelungen zum Datenschutz in Deutschland. Hierzu geh\u00f6rt insbesondere das Gesetz zum Schutz vor Missbrauch personenbezogener Daten bei der Datenverarbeitung (Bundesdatenschutzgesetz \u2013 BDSG). Das BDSG enth\u00e4lt insbesondere Spezialregelungen zum Recht auf Auskunft, zum Recht auf L\u00f6schung, zum Widerspruchsrecht, zur Verarbeitung besonderer Kategorien personenbezogener Daten, zur Verarbeitung f\u00fcr andere Zwecke und zur \u00dcbermittlung sowie automatisierten Entscheidungsfindung im Einzelfall einschlie\u00dflich Profiling. Ferner k\u00f6nnen Landesdatenschutzgesetze der einzelnen Bundesl\u00e4nder zur Anwendung gelangen.   <\/p>\n\n<p><strong>Hinweis auf Geltung DSGVO und Schweizer DSG: <\/strong>Diese Datenschutzhinweise dienen sowohl der Informationserteilung nach dem Schweizer DSG als auch nach der Datenschutzgrundverordnung (DSGVO). Aus diesem Grund bitten wir Sie zu beachten, dass aufgrund der breiteren r\u00e4umlichen Anwendung und Verst\u00e4ndlichkeit die Begriffe der DSGVO verwendet werden. Insbesondere statt der im Schweizer DSG verwendeten Begriffe \u201eBearbeitung\" von \u201ePersonendaten\", &#8221;\u00fcberwiegendes Interesse\" und &#8221;besonders sch\u00fctzenswerte Personendaten\" werden die in der DSGVO verwendeten Begriffe \u201eVerarbeitung\" von \u201epersonenbezogenen Daten\" sowie &#8221;berechtigtes Interesse\" und &#8221;besondere Kategorien von Daten\" verwendet. Die gesetzliche Bedeutung der Begriffe wird jedoch im Rahmen der Geltung des Schweizer DSG weiterhin nach dem Schweizer DSG bestimmt.   <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"m27\">Sicherheitsma\u00dfnahmen<\/h2>\n\n<p>Wir treffen nach Ma\u00dfgabe der gesetzlichen Vorgaben unter Ber\u00fccksichtigung des Stands der Technik, der Implementierungskosten und der Art, des Umfangs, der Umst\u00e4nde und der Zwecke der Verarbeitung sowie der unterschiedlichen Eintrittswahrscheinlichkeiten und des Ausma\u00dfes der Bedrohung der Rechte und Freiheiten nat\u00fcrlicher Personen geeignete technische und organisatorische Ma\u00dfnahmen, um ein dem Risiko angemessenes Schutzniveau zu gew\u00e4hrleisten.<\/p>\n\n<p>Zu den Ma\u00dfnahmen geh\u00f6ren insbesondere die Sicherung der Vertraulichkeit, Integrit\u00e4t und Verf\u00fcgbarkeit von Daten durch Kontrolle des physischen und elektronischen Zugangs zu den Daten als auch des sie betreffenden Zugriffs, der Eingabe, der Weitergabe, der Sicherung der Verf\u00fcgbarkeit und ihrer Trennung. Des Weiteren haben wir Verfahren eingerichtet, die eine Wahrnehmung von Betroffenenrechten, die L\u00f6schung von Daten und Reaktionen auf die Gef\u00e4hrdung der Daten gew\u00e4hrleisten. Ferner ber\u00fccksichtigen wir den Schutz personenbezogener Daten bereits bei der Entwicklung bzw. Auswahl von Hardware, Software sowie Verfahren entsprechend dem Prinzip des Datenschutzes, durch Technikgestaltung und durch datenschutzfreundliche Voreinstellungen.  <\/p>\n\n<p>Sicherung von Online-Verbindungen durch TLS-\/SSL-Verschl\u00fcsselungstechnologie (HTTPS): Um die Daten der Nutzer, die \u00fcber unsere Online-Dienste \u00fcbertragen werden, vor unerlaubten Zugriffen zu sch\u00fctzen, setzen wir auf die TLS-\/SSL-Verschl\u00fcsselungstechnologie. Secure Sockets Layer (SSL) und Transport Layer Security (TLS) sind die Eckpfeiler der sicheren Daten\u00fcbertragung im Internet. Diese Technologien verschl\u00fcsseln die Informationen, die zwischen der Website oder App und dem Browser des Nutzers (oder zwischen zwei Servern) \u00fcbertragen werden, wodurch die Daten vor unbefugtem Zugriff gesch\u00fctzt sind. TLS, als die weiterentwickelte und sicherere Version von SSL, gew\u00e4hrleistet, dass alle Daten\u00fcbertragungen den h\u00f6chsten Sicherheitsstandards entsprechen. Wenn eine Website durch ein SSL-\/TLS-Zertifikat gesichert ist, wird dies durch die Anzeige von HTTPS in der URL signalisiert. Dies dient als ein Indikator f\u00fcr die Nutzer, dass ihre Daten sicher und verschl\u00fcsselt \u00fcbertragen werden.     <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"m25\">\u00dcbermittlung von personenbezogenen Daten<\/h2>\n\n<p>Im Rahmen unserer Verarbeitung von personenbezogenen Daten kommt es vor, dass diese an andere Stellen, Unternehmen, rechtlich selbstst\u00e4ndige Organisationseinheiten oder Personen \u00fcbermittelt beziehungsweise ihnen gegen\u00fcber offengelegt werden. Zu den Empf\u00e4ngern dieser Daten k\u00f6nnen z. B. mit IT-Aufgaben beauftragte Dienstleister geh\u00f6ren oder Anbieter von Diensten und Inhalten, die in eine Website eingebunden sind. In solchen F\u00e4llen beachten wir die gesetzlichen Vorgaben und schlie\u00dfen insbesondere entsprechende Vertr\u00e4ge bzw. Vereinbarungen, die dem Schutz Ihrer Daten dienen, mit den Empf\u00e4ngern Ihrer Daten ab.  <\/p>\n\n<p>Daten\u00fcbermittlung innerhalb der Organisation: Daten\u00fcbermittlung innerhalb der Unternehmensgruppe: Wir k\u00f6nnen personenbezogene Daten an andere Unternehmen innerhalb unserer Unternehmensgruppe \u00fcbermitteln oder ihnen den Zugriff darauf gew\u00e4hren. Sofern die Datenweitergabe zu administrativen Zwecken erfolgt, beruht sie auf unseren berechtigten unternehmerischen und betriebswirtschaftlichen Interessen oder erfolgt, sofern sie zur Erf\u00fcllung unserer vertragsbezogenen Verpflichtungen erforderlich ist beziehungsweise wenn eine Einwilligung der Betroffenen oder eine gesetzliche Erlaubnis vorliegt. <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"m12\">Allgemeine Informationen zur Datenspeicherung und L\u00f6schung<\/h2>\n\n<p>Wir l\u00f6schen personenbezogene Daten, die wir verarbeiten, gem\u00e4\u00df den gesetzlichen Bestimmungen, sobald die zugrundeliegenden Einwilligungen widerrufen werden oder keine weiteren rechtlichen Grundlagen f\u00fcr die Verarbeitung bestehen. Dies betrifft F\u00e4lle, in denen der urspr\u00fcngliche Verarbeitungszweck entf\u00e4llt oder die Daten nicht mehr ben\u00f6tigt werden. Ausnahmen von dieser Regelung bestehen, wenn gesetzliche Pflichten oder besondere Interessen eine l\u00e4ngere Aufbewahrung oder Archivierung der Daten erfordern.  <\/p>\n\n<p>Insbesondere m\u00fcssen Daten, die aus handels- oder steuerrechtlichen Gr\u00fcnden aufbewahrt werden m\u00fcssen oder deren Speicherung notwendig ist zur Rechtsverfolgung oder zum Schutz der Rechte anderer nat\u00fcrlicher oder juristischer Personen, entsprechend archiviert werden.<\/p>\n\n<p>Unsere Datenschutzhinweise enthalten zus\u00e4tzliche Informationen zur Aufbewahrung und L\u00f6schung von Daten, die speziell f\u00fcr bestimmte Verarbeitungsprozesse gelten.<\/p>\n\n<p>Bei mehreren Angaben zur Aufbewahrungsdauer oder L\u00f6schungsfristen eines Datums, ist stets die l\u00e4ngste Frist ma\u00dfgeblich.<\/p>\n\n<p>Beginnt eine Frist nicht ausdr\u00fccklich zu einem bestimmten Datum und betr\u00e4gt sie mindestens ein Jahr, so startet sie automatisch am Ende des Kalenderjahres, in dem das fristausl\u00f6sende Ereignis eingetreten ist. Im Fall laufender Vertragsverh\u00e4ltnisse, in deren Rahmen Daten gespeichert werden, ist das fristausl\u00f6sende Ereignis der Zeitpunkt des Wirksamwerdens der K\u00fcndigung oder sonstige Beendigung des Rechtsverh\u00e4ltnisses. <\/p>\n\n<p>Daten, die nicht mehr f\u00fcr den urspr\u00fcnglich vorgesehenen Zweck, sondern aufgrund gesetzlicher Vorgaben oder anderer Gr\u00fcnde aufbewahrt werden, verarbeiten wir ausschlie\u00dflich zu den Gr\u00fcnden, die ihre Aufbewahrung rechtfertigen.<\/p>\n\n<p><strong>Lis\u00e4tietoja k\u00e4sittelytoimista, -menettelyist\u00e4 ja -palveluista:<\/strong><\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Aufbewahrung und L\u00f6schung von Daten: <\/strong>Die folgenden allgemeinen Fristen gelten f\u00fcr die Aufbewahrung und Archivierung nach deutschem Recht:\n<ul class=\"wp-block-list\">\n<li>10 Jahre - Aufbewahrungsfrist f\u00fcr B\u00fccher und Aufzeichnungen, Jahresabschl\u00fcsse, Inventare, Lageberichte, Er\u00f6ffnungsbilanz sowie die zu ihrem Verst\u00e4ndnis erforderlichen Arbeitsanweisungen und sonstigen Organisationsunterlagen, Buchungsbelege und Rechnungen (\u00a7 147 Abs. 3 i. V. m. Abs. 1 Nr. 1, 4 und 4a AO, \u00a7 14b Abs. 1 UStG, \u00a7 257 Abs. 1 Nr. 1 u. 4, Abs. 4 HGB).<\/li>\n\n\n\n<li>6 Jahre - \u00dcbrige Gesch\u00e4ftsunterlagen: empfangene Handels- oder Gesch\u00e4ftsbriefe, Wiedergaben der abgesandten Handels- oder Gesch\u00e4ftsbriefe, sonstige Unterlagen, soweit sie f\u00fcr die Besteuerung von Bedeutung sind, z. B. Stundenlohnzettel, Betriebsabrechnungsb\u00f6gen, Kalkulationsunterlagen, Preisauszeichnungen, aber auch Lohnabrechnungsunterlagen, soweit sie nicht bereits Buchungsbelege sind und Kassenstreifen (\u00a7 147 Abs. 3 i. V. m. Abs. 1 Nr. 2, 3, 5 AO, \u00a7 257 Abs. 1 Nr. 2 u. 3, Abs. 4 HGB).<\/li>\n\n\n\n<li>3 Jahre - Daten, die erforderlich sind, um potenzielle Gew\u00e4hrleistungs- und Schadensersatzanspr\u00fcche oder \u00e4hnliche vertragliche Anspr\u00fcche und Rechte zu ber\u00fccksichtigen sowie damit verbundene Anfragen zu bearbeiten, basierend auf fr\u00fcheren Gesch\u00e4ftserfahrungen und \u00fcblichen Branchenpraktiken, werden f\u00fcr die Dauer der regul\u00e4ren gesetzlichen Verj\u00e4hrungsfrist von drei Jahren gespeichert (\u00a7\u00a7 195, 199 BGB).<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\" id=\"m10\">Rechte der betroffenen Personen<\/h2>\n\n<p>Rechte der betroffenen Personen aus der DSGVO: Ihnen stehen als Betroffene nach der DSGVO verschiedene Rechte zu, die sich insbesondere aus Art. 15 bis 21 DSGVO ergeben:<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Widerspruchsrecht: Sie haben das Recht, aus Gr\u00fcnden, die sich aus Ihrer besonderen Situation ergeben, jederzeit gegen die Verarbeitung der Sie betreffenden personenbezogenen Daten, die aufgrund von Art. 6 Abs. 1 lit. e oder f DSGVO erfolgt, Widerspruch einzulegen; dies gilt auch f\u00fcr ein auf diese Bestimmungen gest\u00fctztes Profiling. Werden die Sie betreffenden personenbezogenen Daten verarbeitet, um Direktwerbung zu betreiben, haben Sie das Recht, jederzeit Widerspruch gegen die Verarbeitung der Sie betreffenden personenbezogenen Daten zum Zwecke derartiger Werbung einzulegen; dies gilt auch f\u00fcr das Profiling, soweit es mit solcher Direktwerbung in Verbindung steht.   <\/strong><\/li>\n\n\n\n<li><strong>Widerrufsrecht bei Einwilligungen:<\/strong> Sie haben das Recht, erteilte Einwilligungen jederzeit zu widerrufen.<\/li>\n\n\n\n<li><strong>Auskunftsrecht:<\/strong> Sie haben das Recht, eine Best\u00e4tigung dar\u00fcber zu verlangen, ob betreffende Daten verarbeitet werden und auf Auskunft \u00fcber diese Daten sowie auf weitere Informationen und Kopie der Daten entsprechend den gesetzlichen Vorgaben.<\/li>\n\n\n\n<li><strong>Recht auf Berichtigung:<\/strong> Sie haben entsprechend den gesetzlichen Vorgaben das Recht, die Vervollst\u00e4ndigung der Sie betreffenden Daten oder die Berichtigung der Sie betreffenden unrichtigen Daten zu verlangen.<\/li>\n\n\n\n<li><strong>Recht auf L\u00f6schung und Einschr\u00e4nkung der Verarbeitung:<\/strong> Sie haben nach Ma\u00dfgabe der gesetzlichen Vorgaben das Recht, zu verlangen, dass Sie betreffende Daten unverz\u00fcglich gel\u00f6scht werden, bzw. alternativ nach Ma\u00dfgabe der gesetzlichen Vorgaben eine Einschr\u00e4nkung der Verarbeitung der Daten zu verlangen.<\/li>\n\n\n\n<li><strong>Recht auf Daten\u00fcbertragbarkeit:<\/strong> Sie haben das Recht, Sie betreffende Daten, die Sie uns bereitgestellt haben, nach Ma\u00dfgabe der gesetzlichen Vorgaben in einem strukturierten, g\u00e4ngigen und maschinenlesbaren Format zu erhalten oder deren \u00dcbermittlung an einen anderen Verantwortlichen zu fordern.<\/li>\n\n\n\n<li><strong>Beschwerde bei Aufsichtsbeh\u00f6rde:<\/strong> Sie haben unbeschadet eines anderweitigen verwaltungsrechtlichen oder gerichtlichen Rechtsbehelfs das Recht auf Beschwerde bei einer Aufsichtsbeh\u00f6rde, insbesondere in dem Mitgliedstaat ihres gew\u00f6hnlichen Aufenthaltsorts, ihres Arbeitsplatzes oder des Orts des mutma\u00dflichen Versto\u00dfes, wenn Sie der Ansicht sind, dass die Verarbeitung der Sie betreffenden personenbezogenen Daten gegen die Vorgaben der DSGVO verst\u00f6\u00dft.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\" id=\"m354\">Wahrnehmung von Aufgaben nach Satzung oder Gesch\u00e4ftsordnung<\/h2>\n\n<p>Wir verarbeiten die Daten unserer Mitglieder, Unterst\u00fctzer, Interessenten, Gesch\u00e4ftspartner oder sonstiger Personen (Zusammenfassend &#8221;Betroffene\"), wenn wir mit ihnen in einem Mitgliedschafts- oder sonstigem gesch\u00e4ftlichen Verh\u00e4ltnis stehen und unsere Aufgaben wahrnehmen sowie Empf\u00e4nger von Leistungen und Zuwendungen sind. Im \u00dcbrigen verarbeiten wir die Daten Betroffener auf Grundlage unserer berechtigten Interessen, z. B. wenn es sich um administrative Aufgaben oder \u00d6ffentlichkeitsarbeit handelt. <\/p>\n\n<p>Die hierbei verarbeiteten Daten, die Art, der Umfang und der Zweck und die Erforderlichkeit ihrer Verarbeitung, bestimmen sich nach dem zugrundeliegenden Mitgliedschafts- oder Vertragsverh\u00e4ltnis, aus dem sich auch die Erforderlichkeit etwaiger Datenangaben ergeben (im \u00dcbrigen weisen wir auf erforderliche Daten hin).<\/p>\n\n<p>Wir l\u00f6schen Daten, die zur Erbringung unserer satzungs- und gesch\u00e4ftsm\u00e4\u00dfigen Zwecke nicht mehr erforderlich sind. Dies bestimmt sich entsprechend der jeweiligen Aufgaben und vertraglichen Beziehungen. Wir bewahren die Daten so lange auf, wie sie zur Gesch\u00e4ftsabwicklung, als auch im Hinblick auf etwaige Gew\u00e4hrleistungs- oder Haftungspflichten auf Grundlage unserer berechtigten Interesse an deren Regelung relevant sein k\u00f6nnen. Die Erforderlichkeit der Aufbewahrung der Daten wird regelm\u00e4\u00dfig \u00fcberpr\u00fcft; im \u00dcbrigen gelten die gesetzlichen Aufbewahrungspflichten.   <\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Verarbeitete Datenarten:<\/strong> Bestandsdaten (z. B. der vollst\u00e4ndige Name, Wohnadresse, Kontaktinformationen, Kundennummer, etc.); Kontaktdaten (z. B. Post- und E-Mail-Adressen oder Telefonnummern); Vertragsdaten (z. B. Vertragsgegenstand, Laufzeit, Kundenkategorie). Mitgliederdaten (z.B. pers\u00f6nliche Daten wie Name, Alter, Geschlecht, Kontaktdaten (E-Mail-Adresse, Telefonnummer), Mitgliedsnummer, Informationen \u00fcber Mitgliedsbeitr\u00e4ge, Teilnahme an Veranstaltungen, etc.).<\/li>\n\n\n\n<li><strong>Betroffene Personen:<\/strong> Mitglieder.<\/li>\n\n\n\n<li><strong>Zwecke der Verarbeitung:<\/strong> Kommunikation. Organisations- und Verwaltungsverfahren. <\/li>\n\n\n\n<li><strong>Aufbewahrung und L\u00f6schung:<\/strong> L\u00f6schung entsprechend Angaben im Abschnitt &#8221;Allgemeine Informationen zur Datenspeicherung und L\u00f6schung\".<\/li>\n\n\n\n<li><strong>Rechtsgrundlagen:<\/strong> Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f) DSGVO). Vertrag \u00fcber die Mitgliedschaft (Satzung) (Art. 6 Abs. 1 S. 1 lit. b) DSGVO). <\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\" id=\"m225\">Bereitstellung des Onlineangebots und Webhosting<\/h2>\n\n<p>Wir verarbeiten die Daten der Nutzer, um ihnen unsere Online-Dienste zur Verf\u00fcgung stellen zu k\u00f6nnen. Zu diesem Zweck verarbeiten wir die IP-Adresse des Nutzers, die notwendig ist, um die Inhalte und Funktionen unserer Online-Dienste an den Browser oder das Endger\u00e4t der Nutzer zu \u00fcbermitteln. <\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Verarbeitete Datenarten:<\/strong> Nutzungsdaten (z. B. Seitenaufrufe und Verweildauer, Klickpfade, Nutzungsintensit\u00e4t und -frequenz, verwendete Ger\u00e4tetypen und Betriebssysteme, Interaktionen mit Inhalten und Funktionen); Meta-, Kommunikations- und Verfahrensdaten (z. B. IP-Adressen, Zeitangaben, Identifikationsnummern, beteiligte Personen); Protokolldaten (z. B. Logfiles betreffend Logins oder den Abruf von Daten oder Zugriffszeiten.). Inhaltsdaten (z. B. textliche oder bildliche Nachrichten und Beitr\u00e4ge sowie die sie betreffenden Informationen, wie z. B. Angaben zur Autorenschaft oder Zeitpunkt der Erstellung). <\/li>\n\n\n\n<li><strong>Betroffene Personen:<\/strong> Nutzer (z. B. Webseitenbesucher, Nutzer von Onlinediensten).<\/li>\n\n\n\n<li><strong>Zwecke der Verarbeitung:<\/strong> Bereitstellung unseres Onlineangebotes und Nutzerfreundlichkeit; Informationstechnische Infrastruktur (Betrieb und Bereitstellung von Informationssystemen und technischen Ger\u00e4ten (Computer, Server etc.).). Sicherheitsma\u00dfnahmen.<\/li>\n\n\n\n<li><strong>Aufbewahrung und L\u00f6schung:<\/strong> L\u00f6schung entsprechend Angaben im Abschnitt &#8221;Allgemeine Informationen zur Datenspeicherung und L\u00f6schung\".<\/li>\n\n\n\n<li><strong>Rechtsgrundlagen:<\/strong> Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f) DSGVO).<\/li>\n<\/ul>\n\n<p><strong>Lis\u00e4tietoja k\u00e4sittelytoimista, -menettelyist\u00e4 ja -palveluista:<\/strong><\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Erhebung von Zugriffsdaten und Logfiles: <\/strong>Der Zugriff auf unser Onlineangebot wird in Form von sogenannten &#8221;Server-Logfiles\" protokolliert. Zu den Serverlogfiles k\u00f6nnen die Adresse und der Name der abgerufenen Webseiten und Dateien, Datum und Uhrzeit des Abrufs, \u00fcbertragene Datenmengen, Meldung \u00fcber erfolgreichen Abruf, Browsertyp nebst Version, das Betriebssystem des Nutzers, Referrer URL (die zuvor besuchte Seite) und im Regelfall IP-Adressen und der anfragende Provider geh\u00f6ren. Die Serverlogfiles k\u00f6nnen zum einen zu Sicherheitszwecken eingesetzt werden, z. B. um eine \u00dcberlastung der Server zu vermeiden (insbesondere im Fall von missbr\u00e4uchlichen Angriffen, sogenannten DDoS-Attacken), und zum anderen, um die Auslastung der Server und ihre Stabilit\u00e4t sicherzustellen; <strong>Rechtsgrundlagen:<\/strong> Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f) DSGVO). <strong>L\u00f6schung von Daten:<\/strong> Logfile-Informationen werden f\u00fcr die Dauer von maximal 30 Tagen gespeichert und danach gel\u00f6scht oder anonymisiert. Daten, deren weitere Aufbewahrung zu Beweiszwecken erforderlich ist, sind bis zur endg\u00fcltigen Kl\u00e4rung des jeweiligen Vorfalls von der L\u00f6schung ausgenommen.   <\/li>\n\n\n\n<li><strong>WordPress.com: <\/strong>Hosting und Software f\u00fcr die Erstellung, Bereitstellung und den Betrieb von Websites, Blogs und anderen Onlineangeboten; <strong>Dienstanbieter:<\/strong> Aut O\u2019Mattic A8C Irland Ltd., Grand Canal Dock, 25 Herbert Pl, Dublin, D02 AY86, Irland; <strong>Rechtsgrundlagen:<\/strong> Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f) DSGVO); <strong>Website:<\/strong> <a href=\"https:\/\/wordpress.com\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/wordpress.com<\/a>; <strong>Datenschutzerkl\u00e4rung:<\/strong> <a href=\"https:\/\/automattic.com\/de\/privacy\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/automattic.com\/de\/privacy\/<\/a>; <strong>Auftragsverarbeitungsvertrag:<\/strong> <a href=\"https:\/\/wordpress.com\/support\/data-processing-agreements\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/wordpress.com\/support\/data-processing-agreements\/<\/a>. <strong>Grundlage Drittlandtransfers:<\/strong> Data Privacy Framework (DPF).<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\" id=\"m134\">Einsatz von Cookies<\/h2>\n\n<p>Cookies sind kleine Textdateien bzw. sonstige Speichervermerke, die Informationen auf Endger\u00e4ten speichern und aus ihnen auslesen. Zum Beispiel, um den Log-in-Status in einem Nutzerkonto, einen Warenkorbinhalt in einem E-Shop, die aufgerufenen Inhalte oder verwendete Funktionen eines Onlineangebots zu speichern. Cookies k\u00f6nnen ferner in Bezug auf unterschiedliche Anliegen Einsatz finden, etwa zu Zwecken der Funktionsf\u00e4higkeit, der Sicherheit und des Komforts von Onlineangeboten sowie der Erstellung von Analysen der Besucherstr\u00f6me.  <\/p>\n\n<p><strong>Hinweise zur Einwilligung: <\/strong>Wir setzen Cookies im Einklang mit den gesetzlichen Vorschriften ein. Daher holen wir von den Nutzern eine vorhergehende Einwilligung ein, es sei denn, sie ist laut Gesetzeslage nicht gefordert. Eine Erlaubnis ist insbesondere nicht notwendig, wenn das Speichern und das Auslesen der Informationen, also auch von Cookies, unbedingt erforderlich sind, um den Nutzern einen von ihnen ausdr\u00fccklich gew\u00fcnschten Telemediendienst (also unser Onlineangebot) zur Verf\u00fcgung zu stellen. Die widerrufliche Einwilligung wird ihnen gegen\u00fcber deutlich kommuniziert und enth\u00e4lt die Informationen zur jeweiligen Cookie-Nutzung.   <\/p>\n\n<p><strong>Hinweise zu datenschutzrechtlichen Rechtsgrundlagen: <\/strong>Auf welcher datenschutzrechtlichen Grundlage wir die personenbezogenen Daten der Nutzer mithilfe von Cookies verarbeiten, h\u00e4ngt davon ab, ob wir sie um eine Einwilligung bitten. Falls die Nutzer akzeptieren, ist die Rechtsgrundlage der Verwertung ihrer Daten die erkl\u00e4rte Einwilligung. Andernfalls werden die mithilfe von Cookies verwerteten Daten auf Grundlage unserer berechtigten Interessen (z. B. an einem betriebswirtschaftlichen Betrieb unseres Onlineangebots und der Verbesserung seiner Nutzbarkeit) verarbeitet oder, falls dies im Rahmen der Erf\u00fcllung unserer vertraglichen Pflichten erfolgt, wenn der Einsatz von Cookies erforderlich ist, um unseren vertraglichen Verpflichtungen nachzukommen. Zu welchen Zwecken die Cookies von uns verwertet werden, dar\u00fcber kl\u00e4ren wir im Laufe dieser Datenschutzerkl\u00e4rung oder im Rahmen von unseren Einwilligungs- und Verarbeitungsprozessen auf.   <\/p>\n\n<p><strong>Speicherdauer: <\/strong>Im Hinblick auf die Speicherdauer werden die folgenden Arten von Cookies unterschieden:<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Tempor\u00e4re Cookies (auch: Session- oder Sitzungscookies):<\/strong> Tempor\u00e4re Cookies werden sp\u00e4testens gel\u00f6scht, nachdem ein Nutzer ein Onlineangebot verlassen und sein Endger\u00e4t (z. B. Browser oder mobile Applikation) geschlossen hat.<\/li>\n\n\n\n<li><strong>Permanente Cookies:<\/strong> Permanente Cookies bleiben auch nach dem Schlie\u00dfen des Endger\u00e4ts gespeichert. So k\u00f6nnen beispielsweise der Log-in-Status gespeichert und bevorzugte Inhalte direkt angezeigt werden, wenn der Nutzer eine Website erneut besucht. Ebenso k\u00f6nnen die mithilfe von Cookies erhobenen Nutzerdaten zur Reichweitenmessung Verwendung finden. Sofern wir Nutzern keine expliziten Angaben zur Art und Speicherdauer von Cookies mitteilen (z. B. im Rahmen der Einholung der Einwilligung), sollten sie davon ausgehen, dass diese permanent sind und die Speicherdauer bis zu zwei Jahre betragen kann.   <\/li>\n<\/ul>\n\n<p><strong>Allgemeine Hinweise zum Widerruf und Widerspruch (Opt-out): <\/strong>Nutzer k\u00f6nnen die von ihnen abgegebenen Einwilligungen jederzeit widerrufen und zudem einen Widerspruch gegen die Verarbeitung entsprechend den gesetzlichen Vorgaben, auch mittels der Privatsph\u00e4re-Einstellungen ihres Browsers, erkl\u00e4ren.<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Verarbeitete Datenarten:<\/strong> Meta-, Kommunikations- und Verfahrensdaten (z. B. IP-Adressen, Zeitangaben, Identifikationsnummern, beteiligte Personen).<\/li>\n\n\n\n<li><strong>Betroffene Personen:<\/strong> Nutzer (z. B. Webseitenbesucher, Nutzer von Onlinediensten).<\/li>\n\n\n\n<li><strong>Rechtsgrundlagen:<\/strong> Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f) DSGVO). Einwilligung (Art. 6 Abs. 1 S. 1 lit. a) DSGVO). <\/li>\n<\/ul>\n\n<p><strong>Lis\u00e4tietoja k\u00e4sittelytoimista, -menettelyist\u00e4 ja -palveluista:<\/strong><\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Verarbeitung von Cookie-Daten auf Grundlage einer Einwilligung: <\/strong>Wir setzen eine Einwilligungs-Management-L\u00f6sung ein, bei der die Einwilligung der Nutzer zur Verwendung von Cookies oder zu den im Rahmen der Einwilligungs-Management-L\u00f6sung genannten Verfahren und Anbietern eingeholt wird. Dieses Verfahren dient der Einholung, Protokollierung, Verwaltung und dem Widerruf von Einwilligungen, insbesondere bezogen auf den Einsatz von Cookies und vergleichbaren Technologien, die zur Speicherung, zum Auslesen und zur Verarbeitung von Informationen auf den Endger\u00e4ten der Nutzer eingesetzt werden. Im Rahmen dieses Verfahrens werden die Einwilligungen der Nutzer f\u00fcr die Nutzung von Cookies und die damit verbundenen Verarbeitungen von Informationen, einschlie\u00dflich der im Einwilligungs-Management-Verfahren genannten spezifischen Verarbeitungen und Anbieter, eingeholt. Die Nutzer haben zudem die M\u00f6glichkeit, ihre Einwilligungen zu verwalten und zu widerrufen. Die Einwilligungserkl\u00e4rungen werden gespeichert, um eine erneute Abfrage zu vermeiden und den Nachweis der Einwilligung gem\u00e4\u00df der gesetzlichen Anforderungen f\u00fchren zu k\u00f6nnen. Die Speicherung erfolgt serverseitig und\/oder in einem Cookie (sogenanntes Opt-In-Cookie) oder mittels vergleichbarer Technologien, um die Einwilligung einem spezifischen Nutzer oder dessen Ger\u00e4t zuordnen zu k\u00f6nnen. Sofern keine spezifischen Angaben zu den Anbietern von Einwilligungs-Management-Diensten vorliegen, gelten folgende allgemeine Hinweise: Die Dauer der Speicherung der Einwilligung betr\u00e4gt bis zu zwei Jahre. Dabei wird ein pseudonymer Nutzer-Identifikator erstellt, der zusammen mit dem Zeitpunkt der Einwilligung, den Angaben zum Umfang der Einwilligung (z. B. betreffende Kategorien von Cookies und\/oder Diensteanbieter) sowie Informationen \u00fcber den Browser, das System und das verwendete Endger\u00e4t gespeichert wird; <strong>Rechtsgrundlagen:<\/strong> Einwilligung (Art. 6 Abs. 1 S. 1 lit. a) DSGVO).       <\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\" id=\"m17\">Newsletter und elektronische Benachrichtigungen<\/h2>\n\n<p>Wir versenden Newsletter, E-Mails und weitere elektronische Benachrichtigungen (nachfolgend \u201eNewsletter\") ausschlie\u00dflich mit der Einwilligung der Empf\u00e4nger oder aufgrund einer gesetzlichen Grundlage. Sofern im Rahmen einer Anmeldung zum Newsletter dessen Inhalte genannt werden, sind diese Inhalte f\u00fcr die Einwilligung der Nutzer ma\u00dfgeblich. F\u00fcr die Anmeldung zu unserem Newsletter ist normalerweise die Angabe Ihrer E-Mail-Adresse ausreichend. Um Ihnen jedoch einen personalisierten Service bieten zu k\u00f6nnen, bitten wir gegebenenfalls um die Angabe Ihres Namens f\u00fcr eine pers\u00f6nliche Ansprache im Newsletter oder um weitere Informationen, falls diese f\u00fcr den Zweck des Newsletters notwendig sind.   <\/p>\n\n<p>L\u00f6schung und Einschr\u00e4nkung der Verarbeitung: Wir k\u00f6nnen die ausgetragenen E-Mail-Adressen bis zu drei Jahren auf Grundlage unserer berechtigten Interessen speichern, bevor wir sie l\u00f6schen, um eine ehemals gegebene Einwilligung nachweisen zu k\u00f6nnen. Die Verarbeitung dieser Daten wird auf den Zweck einer potenziellen Abwehr von Anspr\u00fcchen beschr\u00e4nkt. Ein individueller L\u00f6schungsantrag ist jederzeit m\u00f6glich, sofern zugleich das ehemalige Bestehen einer Einwilligung best\u00e4tigt wird. Im Fall von Pflichten zur dauerhaften Beachtung von Widerspr\u00fcchen behalten wir uns die Speicherung der E-Mail-Adresse alleine zu diesem Zweck in einer Sperrliste (sogenannte \u201eBlocklist\") vor.   <\/p>\n\n<p>Die Protokollierung des Anmeldeverfahrens erfolgt auf Grundlage unserer berechtigten Interessen zum Zweck des Nachweises seines ordnungsgem\u00e4\u00dfen Ablaufs. Soweit wir einen Dienstleister mit dem Versand von E-Mails beauftragen, erfolgt dies auf Grundlage unserer berechtigten Interessen an einem effizienten und sicheren Versandsystem. <\/p>\n\n<p><strong>Inhalte:<\/strong><\/p>\n\n<p>Informationen zu uns, unseren Leistungen, Aktionen und Angeboten.<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Verarbeitete Datenarten:<\/strong> Bestandsdaten (z. B. der vollst\u00e4ndige Name, Wohnadresse, Kontaktinformationen, Kundennummer, etc.); Kontaktdaten (z. B. Post- und E-Mail-Adressen oder Telefonnummern); Meta-, Kommunikations- und Verfahrensdaten (z. B. IP-Adressen, Zeitangaben, Identifikationsnummern, beteiligte Personen). Nutzungsdaten (z. B. Seitenaufrufe und Verweildauer, Klickpfade, Nutzungsintensit\u00e4t und -frequenz, verwendete Ger\u00e4tetypen und Betriebssysteme, Interaktionen mit Inhalten und Funktionen). <\/li>\n\n\n\n<li><strong>Betroffene Personen:<\/strong> Kommunikationspartner.<\/li>\n\n\n\n<li><strong>Zwecke der Verarbeitung:<\/strong> Direktmarketing (z. B. per E-Mail oder postalisch).<\/li>\n\n\n\n<li><strong>Aufbewahrung und L\u00f6schung:<\/strong>  3 Jahre - Vertragliche Anspr\u00fcche (AT) (Daten, die erforderlich sind, um potenzielle Gew\u00e4hrleistungs- und Schadensersatzanspr\u00fcche oder \u00e4hnliche vertragliche Anspr\u00fcche und Rechte zu ber\u00fccksichtigen sowie damit verbundene Anfragen zu bearbeiten, basierend auf fr\u00fcheren Gesch\u00e4ftserfahrungen und \u00fcblichen Branchenpraktiken, werden f\u00fcr die Dauer der regul\u00e4ren gesetzlichen Verj\u00e4hrungsfrist von drei Jahren gespeichert (\u00a7\u00a7 1478, 1480 ABGB).). 10 Jahre - Vertragliche Anspr\u00fcche (CH) (Daten, die zur Ber\u00fccksichtigung potenzieller Schadenersatzanspr\u00fcche oder \u00e4hnlicher vertraglicher Anspr\u00fcche und Rechte notwendig sind, sowie f\u00fcr die Bearbeitung damit verbundener Anfragen, basierend auf fr\u00fcheren Gesch\u00e4ftserfahrungen und den \u00fcblichen Branchenpraktiken, werden f\u00fcr den Zeitraum der gesetzlichen Verj\u00e4hrungsfrist von zehn Jahren gespeichert, es sei denn, eine k\u00fcrzere Frist von 5 Jahren ist ma\u00dfgeblich, die in bestimmten F\u00e4llen einschl\u00e4gig ist (Art. 127, 130 OR)).<\/li>\n\n\n\n<li><strong>Rechtsgrundlagen:<\/strong> Einwilligung (Art. 6 Abs. 1 S. 1 lit. a) DSGVO). Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f) DSGVO). <\/li>\n\n\n\n<li><strong>Widerspruchsm\u00f6glichkeit (Opt-Out): <\/strong>Sie k\u00f6nnen den Empfang unseres Newsletters jederzeit k\u00fcndigen, d. .h. Ihre Einwilligungen widerrufen, bzw. dem weiteren Empfang widersprechen. Einen Link zur K\u00fcndigung des Newsletters finden Sie entweder am Ende eines jeden Newsletters oder k\u00f6nnen sonst eine der oben angegebenen Kontaktm\u00f6glichkeiten, vorzugsw\u00fcrdig E-Mail, hierzu nutzen.<\/li>\n<\/ul>\n\n<p><strong>Lis\u00e4tietoja k\u00e4sittelytoimista, -menettelyist\u00e4 ja -palveluista:<\/strong><\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Messung von \u00d6ffnungs- und Klickraten: <\/strong>Die Newsletter enthalten einen sogenannten \u201eWeb Beacons\", d. h. eine pixelgro\u00dfe Datei, die beim \u00d6ffnen des Newsletters von unserem bzw. dessen Server, sofern wir einen Versanddienstleister einsetzen, abgerufen wird. Im Rahmen dieses Abrufs werden zun\u00e4chst sowohl technische Informationen, wie beispielsweise Angaben zum Browser und Ihrem System, als auch Ihre IP-Adresse und der Zeitpunkt des Abrufs erhoben. Diese Informationen werden zur technischen Verbesserung unseres Newsletters anhand der technischen Daten oder der Zielgruppen und ihres Leseverhaltens auf Basis ihrer Abruforte (die mithilfe der IP-Adresse bestimmbar sind) oder der Zugriffszeiten genutzt. Diese Analyse beinhaltet ebenfalls die Feststellung, ob und wann die Newsletter ge\u00f6ffnet und welche Links angeklickt werden. Die Informationen werden den einzelnen Newsletterempf\u00e4ngern zugeordnet und in deren Profilen bis zur L\u00f6schung gespeichert. Die Auswertungen dienen dazu, die Lesegewohnheiten unserer Nutzer zu erkennen und unsere Inhalte an sie anzupassen oder unterschiedliche Inhalte entsprechend den Interessen unserer Nutzer zu versenden. Die Messung der \u00d6ffnungs- und Klickraten sowie die Speicherung der Messergebnisse in den Profilen der Nutzer - Dieser Textbereich muss mit einer Premium Lizenz freischaltet werden. - premiumtext premiumtext premiumtext premiumtext premiumtext premiumtext premiumtext premiumtext premiumtext premiumtext premiumtext premiumtext premiumtext premiumtext premiumtext premiumtext premiumtext premiumtext premiumtext premiumtext premiumtext premiumtext premiumtext premiumtext premiumtext premiumtext premiumtext premiumtext premiumtext premiumtext premiumtext premiumtext premiumtext premiumtext premiumtext premiumtext premiumtext premiumtext premiumtext premiumtext premiumtext premiumtext ; <strong>Rechtsgrundlagen:<\/strong> Einwilligung (Art. 6 Abs. 1 S. 1 lit. a) DSGVO).       <\/li>\n\n\n\n<li><strong>CleverReach: <\/strong>E-Mail-Versand- und Automatisierungsdienste; <strong>Dienstanbieter:<\/strong> CleverReach GmbH &amp; Co. KG, \/\/CRASH Building, Schafj\u00fcckenweg 2, 26180 Rastede, Deutschland; <strong>Rechtsgrundlagen:<\/strong> Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f) DSGVO); <strong>Website:<\/strong> <a href=\"https:\/\/www.cleverreach.com\/de\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.cleverreach.com\/de<\/a>; <strong>Datenschutzerkl\u00e4rung:<\/strong> <a href=\"https:\/\/www.cleverreach.com\/de\/datenschutz\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.cleverreach.com\/de\/datenschutz\/<\/a>. <strong>Auftragsverarbeitungsvertrag:<\/strong> Wird vom Dienstanbieter bereitgestellt.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\" id=\"m263\">Webanalyse, Monitoring und Optimierung<\/h2>\n\n<p>Die Webanalyse (auch als \u201eReichweitenmessung\" bezeichnet) dient der Auswertung der Besucherstr\u00f6me unseres Onlineangebots und kann Verhalten, Interessen oder demografische Informationen zu den Besuchern, wie beispielsweise Alter oder Geschlecht, als pseudonyme Werte umfassen. Mithilfe der Reichweitenanalyse k\u00f6nnen wir zum Beispiel erkennen, zu welcher Zeit unser Onlineangebot oder dessen Funktionen beziehungsweise Inhalte am h\u00e4ufigsten genutzt werden, oder zur Wiederverwendung einladen. Ebenso ist es uns m\u00f6glich, nachzuvollziehen, welche Bereiche der Optimierung bed\u00fcrfen.  <\/p>\n\n<p>Neben der Webanalyse k\u00f6nnen wir auch Testverfahren einsetzen, um etwa unterschiedliche Versionen unseres Onlineangebots oder seiner Bestandteile zu testen und zu optimieren.<\/p>\n\n<p>Sofern nachfolgend nicht anders angegeben, k\u00f6nnen zu diesen Zwecken Profile, also zu einem Nutzungsvorgang zusammengefasste Daten, angelegt und Informationen in einem Browser bzw. in einem Endger\u00e4t gespeichert und dann ausgelesen werden. Zu den erhobenen Angaben geh\u00f6ren insbesondere besuchte Websites und dort genutzte Elemente sowie technische Ausk\u00fcnfte, wie etwa der verwendete Browser, das benutzte Computersystem sowie Angaben zu Nutzungszeiten. Sofern sich Nutzer in die Erhebung ihrer Standortdaten uns gegen\u00fcber oder gegen\u00fcber den Anbietern der von uns eingesetzten Dienste einverstanden erkl\u00e4rt haben, ist auch die Verarbeitung von Standortdaten m\u00f6glich.  <\/p>\n\n<p>Dar\u00fcber hinaus werden die IP-Adressen der Nutzer gespeichert. Jedoch nutzen wir ein IP-Masking-Verfahren (d. h. Pseudonymisierung durch K\u00fcrzung der IP-Adresse) zum Schutz der Nutzer. Generell werden die im Rahmen von Webanalyse, A\/B-Testings und Optimierung keine Klardaten der Nutzer (wie z. B. E-Mail-Adressen oder Namen) gespeichert, sondern Pseudonyme. Das hei\u00dft, wir als auch die Anbieter der eingesetzten Software kennen nicht die tats\u00e4chliche Identit\u00e4t der Nutzer, sondern nur die zum Zweck der jeweiligen Verfahren in deren Profilen gespeicherten Angaben.   <\/p>\n\n<p>Hinweise zu Rechtsgrundlagen: Sofern wir die Nutzer um deren Einwilligung in den Einsatz der Drittanbieter bitten, stellt die Rechtsgrundlage der Datenverarbeitung die Einwilligung dar. Ansonsten werden die Nutzerdaten auf Grundlage unserer berechtigten Interessen (d. h. Interesse an effizienten, wirtschaftlichen und empf\u00e4ngerfreundlichen Leistungen) verarbeitet. In diesem Zusammenhang m\u00f6chten wir Sie auch auf die Informationen zur Verwendung von Cookies in dieser Datenschutzerkl\u00e4rung hinweisen.  <\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Verarbeitete Datenarten:<\/strong> Nutzungsdaten (z. B. Seitenaufrufe und Verweildauer, Klickpfade, Nutzungsintensit\u00e4t und -frequenz, verwendete Ger\u00e4tetypen und Betriebssysteme, Interaktionen mit Inhalten und Funktionen). Meta-, Kommunikations- und Verfahrensdaten (z. B. IP-Adressen, Zeitangaben, Identifikationsnummern, beteiligte Personen). <\/li>\n\n\n\n<li><strong>Betroffene Personen:<\/strong> Nutzer (z. B. Webseitenbesucher, Nutzer von Onlinediensten).<\/li>\n\n\n\n<li><strong>Zwecke der Verarbeitung:<\/strong> Reichweitenmessung (z. B. Zugriffsstatistiken, Erkennung wiederkehrender Besucher); Profile mit nutzerbezogenen Informationen (Erstellen von Nutzerprofilen). Bereitstellung unseres Onlineangebotes und Nutzerfreundlichkeit. <\/li>\n\n\n\n<li><strong>Aufbewahrung und L\u00f6schung:<\/strong> L\u00f6schung entsprechend Angaben im Abschnitt &#8221;Allgemeine Informationen zur Datenspeicherung und L\u00f6schung\". Speicherung von Cookies von bis zu 2 Jahren (Sofern nicht anders angegeben, k\u00f6nnen Cookies und \u00e4hnliche Speichermethoden f\u00fcr einen Zeitraum von zwei Jahren auf den Ger\u00e4ten der Nutzer gespeichert werden.). <\/li>\n\n\n\n<li><strong>Sicherheitsma\u00dfnahmen:<\/strong> IP-Masking (Pseudonymisierung der IP-Adresse).<\/li>\n\n\n\n<li><strong>Rechtsgrundlagen:<\/strong> Einwilligung (Art. 6 Abs. 1 S. 1 lit. a) DSGVO). Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f) DSGVO). <\/li>\n<\/ul>\n\n<p><strong>Lis\u00e4tietoja k\u00e4sittelytoimista, -menettelyist\u00e4 ja -palveluista:<\/strong><\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Google Analytics: <\/strong>Wir verwenden Google Analytics zur Messung und Analyse der Nutzung unseres Onlineangebotes auf der Grundlage einer pseudonymen Nutzeridentifikationsnummer. Diese Identifikationsnummer enth\u00e4lt keine eindeutigen Daten, wie Namen oder E-Mail-Adressen. Sie dient dazu, Analyseinformationen einem Endger\u00e4t zuzuordnen, um zu erkennen, welche Inhalte die Nutzer innerhalb eines oder verschiedener Nutzungsvorg\u00e4nge aufgerufen haben, welche Suchbegriffe sie verwendet haben, diese erneut aufgerufen haben oder mit unserem Onlineangebot interagiert haben. Ebenso werden der Zeitpunkt der Nutzung und deren Dauer gespeichert, sowie die Quellen der Nutzer, die auf unser Onlineangebot verweisen und technische Aspekte ihrer Endger\u00e4te und Browser.<br\/>Dabei werden pseudonyme Profile von Nutzern mit Informationen aus der Nutzung verschiedener Ger\u00e4te erstellt, wobei Cookies eingesetzt werden k\u00f6nnen. Google Analytics protokolliert und speichert keine individuellen IP-Adressen f\u00fcr EU-Nutzer. Analytics stellt jedoch grobe geografische Standortdaten bereit, indem es die folgenden Metadaten von IP-Adressen ableitet: Stadt (und der abgeleitete Breiten- und L\u00e4ngengrad der Stadt), Kontinent, Land, Region, Subkontinent (und ID-basierte Gegenst\u00fccke). Beim EU-Datenverkehr werden die IP-Adressdaten ausschlie\u00dflich f\u00fcr diese Ableitung von Geolokalisierungsdaten verwendet, bevor sie sofort gel\u00f6scht werden. Sie werden nicht protokolliert, sind nicht zug\u00e4nglich und werden nicht f\u00fcr weitere Verwendungszwecke genutzt.        Wenn Google Analytics Messdaten sammelt, werden alle IP-Abfragen auf EU-basierten Servern durchgef\u00fchrt, bevor der Verkehr zur Verarbeitung an Analytics-Server weitergeleitet wird; <strong>Dienstanbieter:<\/strong> Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irland; <strong>Rechtsgrundlagen:<\/strong> Einwilligung (Art. 6 Abs. 1 S. 1 lit. a) DSGVO); <strong>Website:<\/strong> <a href=\"https:\/\/marketingplatform.google.com\/intl\/de\/about\/analytics\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/marketingplatform.google.com\/intl\/de\/about\/analytics\/<\/a>; <strong>Sicherheitsma\u00dfnahmen:<\/strong> IP-Masking (Pseudonymisierung der IP-Adresse); <strong>Datenschutzerkl\u00e4rung:<\/strong> <a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/policies.google.com\/privacy<\/a>; <strong>Auftragsverarbeitungsvertrag:<\/strong> <a href=\"https:\/\/business.safety.google\/adsprocessorterms\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/business.safety.google\/adsprocessorterms\/<\/a>; <strong>Grundlage Drittlandtransfers:<\/strong> Data Privacy Framework (DPF); <strong>Widerspruchsm\u00f6glichkeit (Opt-Out):<\/strong> Opt-Out-Plugin: <a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de<\/a>, Einstellungen f\u00fcr die Darstellung von Werbeeinblendungen: <a href=\"https:\/\/myadcenter.google.com\/personalizationoff\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/myadcenter.google.com\/personalizationoff<\/a>. <strong>Weitere Informationen:<\/strong> <a href=\"https:\/\/business.safety.google\/adsservices\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/business.safety.google\/adsservices\/<\/a> (Arten der Verarbeitung sowie der verarbeiteten Daten).<\/li>\n\n\n\n<li><strong>Google Tag Manager: <\/strong>Wir verwenden den Google Tag Manager, eine Software von Google, das es uns erm\u00f6glicht, sogenannte Website-Tags zentral \u00fcber eine Benutzeroberfl\u00e4che zu verwalten. Tags sind kleine Code-Elemente auf unserer Webseite, die dazu dienen, Besucheraktivit\u00e4ten zu erfassen und zu analysieren. Diese Technologie unterst\u00fctzt uns dabei, unsere Webseite und die darauf angebotenen Inhalte zu verbessern. Der Google Tag Manager selbst erstellt keine Nutzerprofile, speichert keine Cookies mit Nutzerprofilen und f\u00fchrt keine eigenst\u00e4ndigen Analysen durch. Seine Funktion beschr\u00e4nkt sich darauf, die Einbindung und Verwaltung von Tools und Diensten, die wir auf unserer Webseite nutzen, zu vereinfachen und effizienter zu gestalten. Trotzdem wird bei der Nutzung des Google Tag Managers die IP-Adresse der Nutzer an Google \u00fcbermittelt, was aus technischen Gr\u00fcnden erforderlich ist, um die von uns verwendeten Dienste zu implementieren. Auch k\u00f6nnen dabei Cookies gesetzt werden. Diese Datenverarbeitung erfolgt jedoch nur, wenn \u00fcber den Tag Manager Dienste eingebunden werden. F\u00fcr genauere Informationen zu diesen Diensten und ihrer Datenverarbeitung verweisen wir auf die weiterf\u00fchrenden Abschnitte dieser Datenschutzerkl\u00e4rung; <strong>Dienstanbieter:<\/strong> Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irland; <strong>Rechtsgrundlagen:<\/strong> Einwilligung (Art. 6 Abs. 1 S. 1 lit. a) DSGVO); <strong>Website:<\/strong> <a href=\"https:\/\/marketingplatform.google.com\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/marketingplatform.google.com<\/a>; <strong>Datenschutzerkl\u00e4rung:<\/strong> <a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/policies.google.com\/privacy<\/a>; <strong>Auftragsverarbeitungsvertrag:<\/strong>        <br\/><a href=\"https:\/\/business.safety.google\/adsprocessorterms\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/business.safety.google\/adsprocessorterms<\/a>. <strong>Grundlage Drittlandtransfers:<\/strong> Data Privacy Framework (DPF).<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\" id=\"m136\">Pr\u00e4senzen in sozialen Netzwerken (Social Media)<\/h2>\n\n<p>Wir unterhalten Onlinepr\u00e4senzen innerhalb sozialer Netzwerke und verarbeiten in diesem Rahmen Nutzerdaten, um mit den dort aktiven Nutzern zu kommunizieren oder Informationen \u00fcber uns anzubieten.<\/p>\n\n<p>Wir weisen darauf hin, dass dabei Nutzerdaten au\u00dferhalb des Raumes der Europ\u00e4ischen Union verarbeitet werden k\u00f6nnen. Hierdurch k\u00f6nnen sich f\u00fcr die Nutzer Risiken ergeben, weil so zum Beispiel die Durchsetzung der Nutzerrechte erschwert werden k\u00f6nnte. <\/p>\n\n<p>Ferner werden die Daten der Nutzer innerhalb sozialer Netzwerke im Regelfall f\u00fcr Marktforschungs- und Werbezwecke verarbeitet. So k\u00f6nnen beispielsweise anhand des Nutzungsverhaltens und sich daraus ergebender Interessen der Nutzer Nutzungsprofile erstellt werden. Letztere finden m\u00f6glicherweise wiederum Verwendung, um etwa Werbeanzeigen innerhalb und au\u00dferhalb der Netzwerke zu schalten, die mutma\u00dflich den Interessen der Nutzer entsprechen. Daher werden im Regelfall Cookies auf den Rechnern der Nutzer gespeichert, in denen das Nutzungsverhalten und die Interessen der Nutzer gespeichert werden. Zudem k\u00f6nnen in den Nutzungsprofilen auch Daten unabh\u00e4ngig der von den Nutzern verwendeten Ger\u00e4ten gespeichert werden (insbesondere, wenn sie Mitglieder der jeweiligen Plattformen und dort eingeloggt sind).    <\/p>\n\n<p>F\u00fcr eine detaillierte Darstellung der jeweiligen Verarbeitungsformen und der Widerspruchsm\u00f6glichkeiten (Opt-out) verweisen wir auf die Datenschutzerkl\u00e4rungen und Angaben der Betreiber der jeweiligen Netzwerke.<\/p>\n\n<p>Auch im Fall von Auskunftsanfragen und der Geltendmachung von Betroffenenrechten weisen wir darauf hin, dass diese am effektivsten bei den Anbietern geltend gemacht werden k\u00f6nnen. Nur Letztere haben jeweils Zugriff auf die Nutzerdaten und k\u00f6nnen direkt entsprechende Ma\u00dfnahmen ergreifen und Ausk\u00fcnfte geben. Sollten Sie dennoch Hilfe ben\u00f6tigen, dann k\u00f6nnen Sie sich an uns wenden.  <\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Verarbeitete Datenarten:<\/strong> Kontaktdaten (z. B. Post- und E-Mail-Adressen oder Telefonnummern); Inhaltsdaten (z. B. textliche oder bildliche Nachrichten und Beitr\u00e4ge sowie die sie betreffenden Informationen, wie z. B. Angaben zur Autorenschaft oder Zeitpunkt der Erstellung). Nutzungsdaten (z. B. Seitenaufrufe und Verweildauer, Klickpfade, Nutzungsintensit\u00e4t und -frequenz, verwendete Ger\u00e4tetypen und Betriebssysteme, Interaktionen mit Inhalten und Funktionen). <\/li>\n\n\n\n<li><strong>Betroffene Personen:<\/strong> Nutzer (z. B. Webseitenbesucher, Nutzer von Onlinediensten).<\/li>\n\n\n\n<li><strong>Zwecke der Verarbeitung:<\/strong> Kommunikation; Feedback (z. B. Sammeln von Feedback via Online-Formular). \u00d6ffentlichkeitsarbeit. <\/li>\n\n\n\n<li><strong>Aufbewahrung und L\u00f6schung:<\/strong> L\u00f6schung entsprechend Angaben im Abschnitt &#8221;Allgemeine Informationen zur Datenspeicherung und L\u00f6schung\".<\/li>\n\n\n\n<li><strong>Rechtsgrundlagen:<\/strong> Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f) DSGVO).<\/li>\n<\/ul>\n\n<p><strong>Lis\u00e4tietoja k\u00e4sittelytoimista, -menettelyist\u00e4 ja -palveluista:<\/strong><\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Instagram: <\/strong>Soziales Netzwerk, erm\u00f6glicht das Teilen von Fotos und Videos, das Kommentieren und Favorisieren von Beitr\u00e4gen, Nachrichtenversand, Abonnieren von Profilen und Seiten; <strong>Dienstanbieter:<\/strong> Meta Platforms Ireland Limited, Merrion Road, Dublin 4, D04 X2K5, Irland; <strong>Rechtsgrundlagen:<\/strong> Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f) DSGVO); <strong>Website:<\/strong> <a href=\"https:\/\/www.instagram.com\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.instagram.com<\/a>; <strong>Datenschutzerkl\u00e4rung:<\/strong> <a href=\"https:\/\/privacycenter.instagram.com\/policy\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/privacycenter.instagram.com\/policy\/<\/a>. <strong>Grundlage Drittlandtransfers:<\/strong> Data Privacy Framework (DPF).<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\" id=\"m328\">Plug-ins und eingebettete Funktionen sowie Inhalte<\/h2>\n\n<p>Wir binden Funktions- und Inhaltselemente in unser Onlineangebot ein, die von den Servern ihrer jeweiligen Anbieter (nachfolgend als \u201eDrittanbieter\" bezeichnet) bezogen werden. Dabei kann es sich zum Beispiel um Grafiken, Videos oder Stadtpl\u00e4ne handeln (nachfolgend einheitlich als \u201eInhalte\" bezeichnet). <\/p>\n\n<p>Die Einbindung setzt immer voraus, dass die Drittanbieter dieser Inhalte die IP-Adresse der Nutzer verarbeiten, da sie ohne IP-Adresse die Inhalte nicht an deren Browser senden k\u00f6nnten. Die IP-Adresse ist damit f\u00fcr die Darstellung dieser Inhalte oder Funktionen erforderlich. Wir bem\u00fchen uns, nur solche Inhalte zu verwenden, deren jeweilige Anbieter die IP-Adresse lediglich zur Auslieferung der Inhalte anzuwenden. Drittanbieter k\u00f6nnen ferner sogenannte Pixel-Tags (unsichtbare Grafiken, auch als \u201eWeb Beacons\" bezeichnet) f\u00fcr statistische oder Marketingzwecke einsetzen. Durch die \u201ePixel-Tags\" k\u00f6nnen Informationen, wie etwa der Besucherverkehr auf den Seiten dieser Website, ausgewertet werden. Die pseudonymen Informationen k\u00f6nnen dar\u00fcber hinaus in Cookies auf dem Ger\u00e4t der Nutzer gespeichert werden und unter anderem technische Ausk\u00fcnfte zum Browser und zum Betriebssystem, zu verweisenden Websites, zur Besuchszeit sowie weitere Angaben zur Nutzung unseres Onlineangebots enthalten, aber auch mit solchen Informationen aus anderen Quellen verbunden werden.     <\/p>\n\n<p><strong>Hinweise zu Rechtsgrundlagen:<\/strong> Sofern wir die Nutzer um ihre Einwilligung in den Einsatz der Drittanbieter bitten, stellt die Rechtsgrundlage der Datenverarbeitung die Erlaubnis dar. Ansonsten werden die Nutzerdaten auf Grundlage unserer berechtigten Interessen (d. h. Interesse an effizienten, wirtschaftlichen und empf\u00e4ngerfreundlichen Leistungen) verarbeitet. In diesem Zusammenhang m\u00f6chten wir Sie auch auf die Informationen zur Verwendung von Cookies in dieser Datenschutzerkl\u00e4rung hinweisen.  <\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Verarbeitete Datenarten:<\/strong> Nutzungsdaten (z. B. Seitenaufrufe und Verweildauer, Klickpfade, Nutzungsintensit\u00e4t und -frequenz, verwendete Ger\u00e4tetypen und Betriebssysteme, Interaktionen mit Inhalten und Funktionen); Meta-, Kommunikations- und Verfahrensdaten (z. B. IP-Adressen, Zeitangaben, Identifikationsnummern, beteiligte Personen); Bestandsdaten (z. B. der vollst\u00e4ndige Name, Wohnadresse, Kontaktinformationen, Kundennummer, etc.); Kontaktdaten (z. B. Post- und E-Mail-Adressen oder Telefonnummern); Inhaltsdaten (z. B. textliche oder bildliche Nachrichten und Beitr\u00e4ge sowie die sie betreffenden Informationen, wie z. B. Angaben zur Autorenschaft oder Zeitpunkt der Erstellung). Standortdaten (Angaben zur geografischen Position eines Ger\u00e4tes oder einer Person). <\/li>\n\n\n\n<li><strong>Betroffene Personen:<\/strong> Nutzer (z. B. Webseitenbesucher, Nutzer von Onlinediensten).<\/li>\n\n\n\n<li><strong>Zwecke der Verarbeitung:<\/strong> Bereitstellung unseres Onlineangebotes und Nutzerfreundlichkeit.<\/li>\n\n\n\n<li><strong>Aufbewahrung und L\u00f6schung:<\/strong> L\u00f6schung entsprechend Angaben im Abschnitt &#8221;Allgemeine Informationen zur Datenspeicherung und L\u00f6schung\". Speicherung von Cookies von bis zu 2 Jahren (Sofern nicht anders angegeben, k\u00f6nnen Cookies und \u00e4hnliche Speichermethoden f\u00fcr einen Zeitraum von zwei Jahren auf den Ger\u00e4ten der Nutzer gespeichert werden.). <\/li>\n\n\n\n<li><strong>Rechtsgrundlagen:<\/strong> Einwilligung (Art. 6 Abs. 1 S. 1 lit. a) DSGVO). Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f) DSGVO). <\/li>\n<\/ul>\n\n<p><strong>Lis\u00e4tietoja k\u00e4sittelytoimista, -menettelyist\u00e4 ja -palveluista:<\/strong><\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Kolmannen osapuolen ohjelmistojen, skriptien tai kehysten (esim. jQuery) integrointi: <\/strong>Integroimme verkkotarjontaamme ohjelmistoja, jotka haemme muiden palveluntarjoajien palvelimilta (esim. toimintokirjastoja, joita k\u00e4yt\u00e4mme verkkotarjontamme n\u00e4ytt\u00e4miseen tai k\u00e4ytt\u00e4j\u00e4yst\u00e4v\u00e4llisyyteen). Kyseiset palveluntarjoajat ker\u00e4\u00e4v\u00e4t k\u00e4ytt\u00e4jien IP-osoitteen ja voivat k\u00e4sitell\u00e4 sit\u00e4 ohjelmiston siirt\u00e4miseksi k\u00e4ytt\u00e4j\u00e4n selaimelle ja turvallisuussyist\u00e4 sek\u00e4 tarjouksensa arvioimiseksi ja optimoimiseksi. - Integroimme verkkotarjontaamme ohjelmistoja, jotka haemme muiden palveluntarjoajien palvelimilta (esim. toimintokirjastoja, joita k\u00e4yt\u00e4mme verkkotarjontamme n\u00e4ytt\u00e4miseen tai k\u00e4ytt\u00e4j\u00e4yst\u00e4v\u00e4llisyyteen). Kyseiset palveluntarjoajat ker\u00e4\u00e4v\u00e4t k\u00e4ytt\u00e4jien IP-osoitteen ja voivat k\u00e4sitell\u00e4 sit\u00e4 ohjelmiston siirt\u00e4miseksi k\u00e4ytt\u00e4j\u00e4n selaimelle ja turvallisuussyist\u00e4 sek\u00e4 tarjontansa arvioimiseksi ja optimoimiseksi; oikeusperusta: <strong>oikeutetut edut<\/strong> (yleisen tietosuoja-asetuksen 6 artiklan 1 kohdan 1 virkkeen f alakohta).   <\/li>\n\n\n\n<li><strong>Google Fonts (omalla palvelimella): <\/strong> <strong>Palveluntarjoaja: Googlen<\/strong> Google-fonttitiedostot: Google Google-fonttitiedostot: Google-fonttitiedostot (oma palvel <strong>in):<\/strong> Fonttitiedostojen toimittaminen verkkotarjontamme k\u00e4ytt\u00e4j\u00e4yst\u00e4v\u00e4llist\u00e4 esitt\u00e4mist\u00e4 varten: <strong>Oikeusperusta: Oikeutettu etu<\/strong> (yleisen tietosuoja-asetuksen 6 artiklan 1 kohdan 1 virkkeen 1 alakohdan f alakohta).<\/li>\n\n\n\n<li><strong>Google Maps: <\/strong>Googlen tarjoaman &#8221;Google Maps\" -palvelun kartat. K\u00e4siteltyihin tietoihin voi sis\u00e4lty\u00e4 erityisesti IP-osoitteita ja k\u00e4ytt\u00e4j\u00e4n sijaintitietoja <strong>:<\/strong> Google Cloud EMEA Limited, 70 Sir John Rogerson&#8217;s Quay, Dublin 2, Irlanti; Oikeusperusta: Suostumus ( <strong>yleisen tietosuoja-asetuksen 6 artiklan 1 kohdan 1 virkkeen<\/strong> 1 alakohdan a alakohta); Verkkosivusto: https:\/\/mapsplatform.google.com\/; Tietosuojaseloste <strong>: https<\/strong> <a href=\"https:\/\/mapsplatform.google.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">:\/\/policies.google<\/a>. <strong>com\/privacy.<\/strong> <strong>Kolmansiin maihin teht\u00e4vien siirtojen perusta: Data<\/strong> Privacy Framework (DPF). <\/li>\n\n\n\n<li><strong>YouTube-videot: <\/strong> <strong>Palveluntarjoaja:<\/strong> YouTube-videot: Videosis\u00e4lt\u00f6; <strong>Palveluntarjoaja:<\/strong> Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irlanti; Oikeusperusta: Suostumus <strong>(yleisen<\/strong> tietosuoja-aset <strong>uksen 6 artiklan 1 kohdan 1 virkkeen<\/strong> 1 alakohdan a alakohta); Verkkosivusto: https:\/\/www.youtube.com; Tietosuojak\u00e4yt\u00e4nt\u00f6: <strong>https<\/strong> <a href=\"https:\/\/www.youtube.com\" target=\"_blank\" rel=\"noreferrer noopener\">:\/\/policies.google.<\/a> <strong>com\/privacy;<\/strong> <a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noreferrer noopener\">Kolmansiin maihin<\/a> <strong>teht\u00e4vien siirtojen<\/strong> <strong>peruste<\/strong> <strong>: Tietosuojakehys (DPF)<\/strong>. <strong>Mahdollisuus vastustaa (opt-out):<\/strong> Opt-out-liit\u00e4nn\u00e4inen: <a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/tools.google<\/a>.com\/dlpage\/gaoptout?hl=de; Mainosten <a href=\"https:\/\/myadcenter.google.com\/personalizationoff\" target=\"_blank\" rel=\"noreferrer noopener\">n\u00e4ytt\u00e4misen asetukset<\/a>: https:\/\/myadcenter.google.com\/personalizationoff.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\" id=\"m15\">Muuta ja p\u00e4ivit\u00e4<\/h2>\n\n<p>Pyyd\u00e4mme sinua tutustumaan s\u00e4\u00e4nn\u00f6llisesti tietosuojak\u00e4yt\u00e4nt\u00f6mme sis\u00e4lt\u00f6\u00f6n. Muutamme tietosuojak\u00e4yt\u00e4nt\u00f6\u00e4 heti, kun muutokset suorittamassamme tietojenk\u00e4sittelyss\u00e4 tekev\u00e4t sen tarpeelliseksi. Ilmoitamme sinulle heti, kun muutokset edellytt\u00e4v\u00e4t yhteisty\u00f6t\u00e4si (esim. suostumusta) tai muuta yksil\u00f6llist\u00e4 ilmoitusta.  <\/p>\n\n<p>Jos annamme t\u00e4ss\u00e4 tietosuojak\u00e4yt\u00e4nn\u00f6ss\u00e4 yritysten ja organisaatioiden osoitteita ja yhteystietoja, ota huomioon, ett\u00e4 osoitteet saattavat muuttua ajan my\u00f6t\u00e4, ja tarkista tiedot ennen yhteydenottoa.<\/p>\n\n<p><a href=\"https:\/\/datenschutz-generator.de\/\" target=\"_blank\" rel=\"noreferrer noopener\">Luonut ilmainen Datenschutz-Generator.de, jonka on laatinut Dr Thomas Schwenke<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Datenschutzerkl\u00e4rung Stand: 3. September 2024 Inhalts\u00fcbersicht Verantwortlicher David GangiVerband Evangelischer Bekenntnisschulen e.V.Blumentorstr. 1676227 Karlsruhe Vertretungsberechtigte Personen: Prof. Dr. Wolfgang Stock E-Mail-Adresse: datenschutzbeauftragter@vebs.de Impressum: vebs.de\/impressum Datenschutzbeauftragter: Hendrik WeiandDruseltalstra\u00dfe 12534131 KasselE-Mail: weiand@netzwerk-m.de \u00dcbersicht der Verarbeitungen Die nachfolgende \u00dcbersicht fasst die Arten der verarbeiteten Daten und die Zwecke ihrer Verarbeitung zusammen und verweist auf die betroffenen Personen. Arten [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-46109","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Datenschutz - VEBS e.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vebs.de\/fi\/datenschutzerklaerung\/\" \/>\n<meta property=\"og:locale\" content=\"fi_FI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datenschutz - VEBS e.V.\" \/>\n<meta property=\"og:description\" content=\"Datenschutzerkl\u00e4rung Stand: 3. September 2024 Inhalts\u00fcbersicht Verantwortlicher David GangiVerband Evangelischer Bekenntnisschulen e.V.Blumentorstr. 1676227 Karlsruhe Vertretungsberechtigte Personen: Prof. Dr. Wolfgang Stock E-Mail-Adresse: datenschutzbeauftragter@vebs.de Impressum: vebs.de\/impressum Datenschutzbeauftragter: Hendrik WeiandDruseltalstra\u00dfe 12534131 KasselE-Mail: weiand@netzwerk-m.de \u00dcbersicht der Verarbeitungen Die nachfolgende \u00dcbersicht fasst die Arten der verarbeiteten Daten und die Zwecke ihrer Verarbeitung zusammen und verweist auf die betroffenen Personen. Arten [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vebs.de\/fi\/datenschutzerklaerung\/\" \/>\n<meta property=\"og:site_name\" content=\"VEBS e.V.\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-05T09:12:11+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"32 minuuttia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.vebs.de\/fi\/datenschutzerklaerung\/\",\"url\":\"https:\/\/www.vebs.de\/fi\/datenschutzerklaerung\/\",\"name\":\"Datenschutz - VEBS e.V.\",\"isPartOf\":{\"@id\":\"https:\/\/www.vebs.de\/fi\/#website\"},\"datePublished\":\"2020-08-12T12:47:14+00:00\",\"dateModified\":\"2025-09-05T09:12:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.vebs.de\/fi\/datenschutzerklaerung\/#breadcrumb\"},\"inLanguage\":\"fi\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.vebs.de\/fi\/datenschutzerklaerung\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.vebs.de\/fi\/datenschutzerklaerung\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Etusivu\",\"item\":\"https:\/\/www.vebs.de\/fi\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Datenschutz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.vebs.de\/fi\/#website\",\"url\":\"https:\/\/www.vebs.de\/fi\/\",\"name\":\"VEBS e.V.\",\"description\":\"Verband Evangelischer Bekenntnisschulen e.V.\",\"publisher\":{\"@id\":\"https:\/\/www.vebs.de\/fi\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.vebs.de\/fi\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fi\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.vebs.de\/fi\/#organization\",\"name\":\"Verband Evangelischer Bekenntnisschulen e.V. (VEBS)\",\"url\":\"https:\/\/www.vebs.de\/fi\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fi\",\"@id\":\"https:\/\/www.vebs.de\/fi\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.vebs.de\/wp-content\/uploads\/2021\/03\/vebs-Logo-v2_rot_300x177.png\",\"contentUrl\":\"https:\/\/www.vebs.de\/wp-content\/uploads\/2021\/03\/vebs-Logo-v2_rot_300x177.png\",\"width\":300,\"height\":177,\"caption\":\"Verband Evangelischer Bekenntnisschulen e.V. (VEBS)\"},\"image\":{\"@id\":\"https:\/\/www.vebs.de\/fi\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datenschutz - VEBS e.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vebs.de\/fi\/datenschutzerklaerung\/","og_locale":"fi_FI","og_type":"article","og_title":"Datenschutz - VEBS e.V.","og_description":"Datenschutzerkl\u00e4rung Stand: 3. September 2024 Inhalts\u00fcbersicht Verantwortlicher David GangiVerband Evangelischer Bekenntnisschulen e.V.Blumentorstr. 1676227 Karlsruhe Vertretungsberechtigte Personen: Prof. Dr. Wolfgang Stock E-Mail-Adresse: datenschutzbeauftragter@vebs.de Impressum: vebs.de\/impressum Datenschutzbeauftragter: Hendrik WeiandDruseltalstra\u00dfe 12534131 KasselE-Mail: weiand@netzwerk-m.de \u00dcbersicht der Verarbeitungen Die nachfolgende \u00dcbersicht fasst die Arten der verarbeiteten Daten und die Zwecke ihrer Verarbeitung zusammen und verweist auf die betroffenen Personen. Arten [&hellip;]","og_url":"https:\/\/www.vebs.de\/fi\/datenschutzerklaerung\/","og_site_name":"VEBS e.V.","article_modified_time":"2025-09-05T09:12:11+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"32 minuuttia"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vebs.de\/fi\/datenschutzerklaerung\/","url":"https:\/\/www.vebs.de\/fi\/datenschutzerklaerung\/","name":"Datenschutz - VEBS e.V.","isPartOf":{"@id":"https:\/\/www.vebs.de\/fi\/#website"},"datePublished":"2020-08-12T12:47:14+00:00","dateModified":"2025-09-05T09:12:11+00:00","breadcrumb":{"@id":"https:\/\/www.vebs.de\/fi\/datenschutzerklaerung\/#breadcrumb"},"inLanguage":"fi","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vebs.de\/fi\/datenschutzerklaerung\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vebs.de\/fi\/datenschutzerklaerung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Etusivu","item":"https:\/\/www.vebs.de\/fi\/"},{"@type":"ListItem","position":2,"name":"Datenschutz"}]},{"@type":"WebSite","@id":"https:\/\/www.vebs.de\/fi\/#website","url":"https:\/\/www.vebs.de\/fi\/","name":"VEBS e.V.","description":"Verband Evangelischer Bekenntnisschulen e.V.","publisher":{"@id":"https:\/\/www.vebs.de\/fi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vebs.de\/fi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fi"},{"@type":"Organization","@id":"https:\/\/www.vebs.de\/fi\/#organization","name":"Verband Evangelischer Bekenntnisschulen e.V. (VEBS)","url":"https:\/\/www.vebs.de\/fi\/","logo":{"@type":"ImageObject","inLanguage":"fi","@id":"https:\/\/www.vebs.de\/fi\/#\/schema\/logo\/image\/","url":"https:\/\/www.vebs.de\/wp-content\/uploads\/2021\/03\/vebs-Logo-v2_rot_300x177.png","contentUrl":"https:\/\/www.vebs.de\/wp-content\/uploads\/2021\/03\/vebs-Logo-v2_rot_300x177.png","width":300,"height":177,"caption":"Verband Evangelischer Bekenntnisschulen e.V. (VEBS)"},"image":{"@id":"https:\/\/www.vebs.de\/fi\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.vebs.de\/fi\/wp-json\/wp\/v2\/pages\/46109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vebs.de\/fi\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.vebs.de\/fi\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.vebs.de\/fi\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vebs.de\/fi\/wp-json\/wp\/v2\/comments?post=46109"}],"version-history":[{"count":1,"href":"https:\/\/www.vebs.de\/fi\/wp-json\/wp\/v2\/pages\/46109\/revisions"}],"predecessor-version":[{"id":46118,"href":"https:\/\/www.vebs.de\/fi\/wp-json\/wp\/v2\/pages\/46109\/revisions\/46118"}],"wp:attachment":[{"href":"https:\/\/www.vebs.de\/fi\/wp-json\/wp\/v2\/media?parent=46109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}